{"id":20490,"date":"2021-08-11T14:42:04","date_gmt":"2021-08-11T14:42:04","guid":{"rendered":"https:\/\/www.schaaf-gmbh.com\/?page_id=20490"},"modified":"2023-04-25T08:22:37","modified_gmt":"2023-04-25T08:22:37","slug":"chinesisch","status":"publish","type":"page","link":"https:\/\/www.schaaf-gmbh.com\/de\/kontakt\/deutschland\/ansprechpartner-sprachen\/chinesisch\/","title":{"rendered":"Ansprechpartner Chinesisch"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"20490\" class=\"elementor elementor-20490\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0bcee35 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0bcee35\" data-element_type=\"section\" data-e-type=\"section\">\r\n\t\t\r\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d79f63c\" data-id=\"d79f63c\" data-element_type=\"column\" data-e-type=\"column\">\r\n\t\t\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\r\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-294c75e elementor-widget elementor-widget-heading\" data-id=\"294c75e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Ansprechpartner Chinesisch<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/section>\r\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-64fec9d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"64fec9d\" data-element_type=\"section\" data-e-type=\"section\">\r\n\t\t\r\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4b65596\" data-id=\"4b65596\" data-element_type=\"column\" data-e-type=\"column\">\r\n\t\t\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\r\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3b65c22 elementor-widget elementor-widget-shortcode\" data-id=\"3b65c22\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\"><a class=\"btn btn-outline-primary\" href=\"\/de\/kontakt\/deutschland\/ansprechpartner-sprachen\/arabisch\">Arabisch<\/a>\r\n<a class=\"btn btn-outline-primary\" href=\"\/de\/kontakt\/deutschland\/ansprechpartner-sprachen\/chinesisch\">Chinesisch<\/a>\r\n<!--<a class=\"btn btn-outline-primary\" href=\"\/de\/daenisch\">D\u00e4nisch<\/a>-->\r\n<a class=\"btn btn-outline-primary\" href=\"\/de\/kontakt\/deutschland\/ansprechpartner-sprachen\/deutsch\">Deutsch<\/a>\r\n<a class=\"btn btn-outline-primary\" href=\"\/de\/kontakt\/deutschland\/ansprechpartner-sprachen\/englisch\">Englisch<\/a>\r\n<a class=\"btn btn-outline-primary\" href=\"\/de\/kontakt\/deutschland\/ansprechpartner-sprachen\/franzoesisch\">Franz\u00f6sisch<\/a>\r\n<a class=\"btn btn-outline-primary\" href=\"\/de\/kontakt\/deutschland\/ansprechpartner-sprachen\/niederlaendisch\">Niederl\u00e4ndisch<\/a>\r\n<a class=\"btn btn-outline-primary\" href=\"\/de\/kontakt\/deutschland\/ansprechpartner-sprachen\/norwegisch\">Norwegisch<\/a>\r\n<a class=\"btn btn-outline-primary\" href=\"\/de\/kontakt\/deutschland\/ansprechpartner-sprachen\/polnisch\">Polnisch<\/a>\r\n<a class=\"btn btn-outline-primary\" href=\"\/de\/kontakt\/deutschland\/ansprechpartner-sprachen\/russisch\">Russisch<\/a>\r\n<a class=\"btn btn-outline-primary\" href=\"\/de\/kontakt\/deutschland\/ansprechpartner-sprachen\/spanisch\">Spanisch<\/a>\r\n<a class=\"btn btn-outline-primary\" href=\"\/de\/kontakt\/deutschland\/ansprechpartner-sprachen\/tuerkisch\">T\u00fcrkisch<\/a>\r\n\r\n<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/section>\r\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-894e04b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"894e04b\" data-element_type=\"section\" data-e-type=\"section\">\r\n\t\t\r\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3244aa8\" data-id=\"3244aa8\" data-element_type=\"column\" data-e-type=\"column\">\r\n\t\t\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\r\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8a78466 elementor-widget elementor-widget-heading\" data-id=\"8a78466\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Chinesischsprachige Mitarbeiter<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/section>\r\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8d3cc2e tlp-team elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8d3cc2e\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\r\n\t\t\r\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c5d2e25\" data-id=\"c5d2e25\" data-element_type=\"column\" data-e-type=\"column\">\r\n\t\t\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\r\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ce42d30 elementor-widget elementor-widget-tlp-team-pro\" data-id=\"ce42d30\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"tlp-team-pro.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class='rt-container-fluid rt-team-container rt-team-container-20489' id='rt-team-container-742960923'  data-layout='layout3' data-desktop-col='3'  data-tab-col='2'  data-mobile-col='1' data-sc-id='20489' data-popup-bg='''><div data-title='Loading ...' class='rt-row rt-content-loader layout3 ttp-even ttp-pre-loader'><div class='rt-col-md-4 rt-col-sm-6 rt-col-xs-12 even-grid-item rt-grid-item' data-id='8637'><div class=\"single-team-area\"><figure><img fetchpriority=\"high\" decoding=\"async\" width=\"250\" height=\"350\" class=\"img-responsive rt-team-img lazyload\" alt=\"Yong Yan\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" data-src=\"https:\/\/www.schaaf-gmbh.com\/wp-content\/uploads\/mitarbeiter\/yong_yan.jpg\"><\/figure><div class='tlp-content2'><h3><span class=\"team-name\">Yong Yan<\/span><\/h3><div class=\"tlp-position\">Dipl. Kffr. Finanzbuchhaltung \/ Controlling SCHAAF CN<\/div><\/div><div class='contact-info'><ul><li><i class=\"fa fa-envelope-o\"><\/i><a href=\"mailto:yong.yan@schaaf-gmbh.com\"><span class=\"tlp-email\">yong.yan@schaaf-gmbh.com<\/span><\/a><\/li><li><i class=\"fa fa-phone\"><\/i><a href=\"tel:+49-2431-97770-17\" class=\"tlp-phone\">+49-2431-97770-17<\/a><\/li><li><i class=\"fa fa-fax\"><\/i><a href=\"fax:+49-2431-97770-71\" class=\"tlp-phone\">+49-2431-97770-71<\/a><\/li><\/ul><\/div><div class=\"tlp-team-skill\"><div class='skill_name'><img class=\"teamflag lazyload\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" alt=\"Deutsch\" width=\"18\" height=\"12\" data-src=\"https:\/\/www.schaaf-gmbh.com\/wp-content\/plugins\/sitepress-multilingual-cms\/res\/flags\/de.png\"><img class=\"teamflag lazyload\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" alt=\"Englisch\" width=\"18\" height=\"12\" data-src=\"https:\/\/www.schaaf-gmbh.com\/wp-content\/plugins\/sitepress-multilingual-cms\/res\/flags\/gb.png\"><img class=\"teamflag lazyload\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" alt=\"Chinesisch\" width=\"18\" height=\"12\" data-src=\"https:\/\/www.schaaf-gmbh.com\/wp-content\/plugins\/sitepress-multilingual-cms\/res\/flags\/cn.png\"><\/div><\/div><\/div><\/div><div class=\"rt-loading-overlay\"><\/div><div class=\"rt-loading rt-ball-clip-rotate\"><div><\/div><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/section>\r\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-cb03bca elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"cb03bca\" data-element_type=\"section\" data-e-type=\"section\">\r\n\t\t\r\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1a8b2a3\" data-id=\"1a8b2a3\" data-element_type=\"column\" data-e-type=\"column\">\r\n\t\t\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\r\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f01a884 elementor-widget elementor-widget-shortcode\" data-id=\"f01a884\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\"><a class=\"btn btn-outline-primary\" href=\"\/de\/kontakt\/deutschland\/ansprechpartner-sprachen\/arabisch\">Arabisch<\/a>\r\n<a class=\"btn btn-outline-primary\" href=\"\/de\/kontakt\/deutschland\/ansprechpartner-sprachen\/chinesisch\">Chinesisch<\/a>\r\n<!--<a class=\"btn btn-outline-primary\" href=\"\/de\/daenisch\">D\u00e4nisch<\/a>-->\r\n<a class=\"btn btn-outline-primary\" href=\"\/de\/kontakt\/deutschland\/ansprechpartner-sprachen\/deutsch\">Deutsch<\/a>\r\n<a class=\"btn btn-outline-primary\" href=\"\/de\/kontakt\/deutschland\/ansprechpartner-sprachen\/englisch\">Englisch<\/a>\r\n<a class=\"btn btn-outline-primary\" href=\"\/de\/kontakt\/deutschland\/ansprechpartner-sprachen\/franzoesisch\">Franz\u00f6sisch<\/a>\r\n<a class=\"btn btn-outline-primary\" href=\"\/de\/kontakt\/deutschland\/ansprechpartner-sprachen\/niederlaendisch\">Niederl\u00e4ndisch<\/a>\r\n<a class=\"btn btn-outline-primary\" href=\"\/de\/kontakt\/deutschland\/ansprechpartner-sprachen\/norwegisch\">Norwegisch<\/a>\r\n<a class=\"btn btn-outline-primary\" href=\"\/de\/kontakt\/deutschland\/ansprechpartner-sprachen\/polnisch\">Polnisch<\/a>\r\n<a class=\"btn btn-outline-primary\" href=\"\/de\/kontakt\/deutschland\/ansprechpartner-sprachen\/russisch\">Russisch<\/a>\r\n<a class=\"btn btn-outline-primary\" href=\"\/de\/kontakt\/deutschland\/ansprechpartner-sprachen\/spanisch\">Spanisch<\/a>\r\n<a class=\"btn btn-outline-primary\" href=\"\/de\/kontakt\/deutschland\/ansprechpartner-sprachen\/tuerkisch\">T\u00fcrkisch<\/a>\r\n\r\n<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/section>\r\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-139f71e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"139f71e\" data-element_type=\"section\" data-e-type=\"section\">\r\n\t\t\r\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c728a8c\" data-id=\"c728a8c\" data-element_type=\"column\" data-e-type=\"column\">\r\n\t\t\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\r\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-367cdbc elementor-widget elementor-widget-template\" data-id=\"367cdbc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"template.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-template\">\n\t\t\t\t\t<div data-elementor-type=\"section\" data-elementor-id=\"51128\" class=\"elementor elementor-51128\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5825bf07 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5825bf07\" data-element_type=\"section\" data-e-type=\"section\">\r\n\t\t\r\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-71d753b9 elementor-invisible\" data-id=\"71d753b9\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeIn&quot;}\">\r\n\t\t\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\r\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-10c204ce elementor-widget elementor-widget-image\" data-id=\"10c204ce\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"\/de\/kontakt\/deutschland\/\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"768\" height=\"530\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" class=\"elementor-animation-float attachment-medium_large size-medium_large wp-image-1206 lazyload\" alt=\"Schaaf Mitarbeiter formen das Schaaf Firmenlogo\" sizes=\"(max-width: 768px) 100vw, 768px\" data-src=\"https:\/\/www.schaaf-gmbh.com\/wp-content\/uploads\/grundaufbau\/schaaf_ansprechpartner_mitarbeiter-768x530.jpg\" data-srcset=\"https:\/\/www.schaaf-gmbh.com\/wp-content\/uploads\/grundaufbau\/schaaf_ansprechpartner_mitarbeiter-768x530.jpg 768w, https:\/\/www.schaaf-gmbh.com\/wp-content\/uploads\/grundaufbau\/schaaf_ansprechpartner_mitarbeiter-640x442.jpg 640w, https:\/\/www.schaaf-gmbh.com\/wp-content\/uploads\/grundaufbau\/schaaf_ansprechpartner_mitarbeiter-400x276.jpg 400w, https:\/\/www.schaaf-gmbh.com\/wp-content\/uploads\/grundaufbau\/schaaf_ansprechpartner_mitarbeiter-367x253.jpg 367w\">\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3aa3e432 elementor-widget elementor-widget-heading\" data-id=\"3aa3e432\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><a href=\"\/de\/kontakt\/deutschland\/\">Ansprechpartner<\/a><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-7a58ee65 elementor-invisible\" data-id=\"7a58ee65\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeIn&quot;}\">\r\n\t\t\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\r\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2ecd5b43 elementor-widget elementor-widget-image\" data-id=\"2ecd5b43\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"\/de\/kontakt\/auslandsvertretung\/\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"768\" height=\"530\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" class=\"elementor-animation-float attachment-medium_large size-medium_large wp-image-6528 lazyload\" alt=\"Weltkarte\" sizes=\"(max-width: 768px) 100vw, 768px\" data-src=\"https:\/\/www.schaaf-gmbh.com\/wp-content\/uploads\/grundaufbau\/weltkarte-1-768x530.jpg\" data-srcset=\"https:\/\/www.schaaf-gmbh.com\/wp-content\/uploads\/grundaufbau\/weltkarte-1-768x530.jpg 768w, https:\/\/www.schaaf-gmbh.com\/wp-content\/uploads\/grundaufbau\/weltkarte-1-640x442.jpg 640w, https:\/\/www.schaaf-gmbh.com\/wp-content\/uploads\/grundaufbau\/weltkarte-1-400x276.jpg 400w, https:\/\/www.schaaf-gmbh.com\/wp-content\/uploads\/grundaufbau\/weltkarte-1-367x253.jpg 367w\">\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4a48ed05 elementor-widget elementor-widget-heading\" data-id=\"4a48ed05\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><a href=\"\/de\/kontakt\/auslandsvertretung\/\">Auslandsvertretung<\/a><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-5d5fd6d6 elementor-invisible\" data-id=\"5d5fd6d6\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeIn&quot;}\">\r\n\t\t\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\r\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4b807c92 elementor-widget elementor-widget-image\" data-id=\"4b807c92\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"\/de\/unternehmen\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"707\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" class=\"elementor-animation-float attachment-large size-large wp-image-6545 lazyload\" alt=\"Schaaf Geb\u00e4ude in Erkelenz, Deutschland\" sizes=\"(max-width: 1024px) 100vw, 1024px\" data-src=\"https:\/\/www.schaaf-gmbh.com\/wp-content\/uploads\/unternehmen\/schaaf_deutschland-1024x707.jpg\" data-srcset=\"https:\/\/www.schaaf-gmbh.com\/wp-content\/uploads\/unternehmen\/schaaf_deutschland-1024x707.jpg 1024w, https:\/\/www.schaaf-gmbh.com\/wp-content\/uploads\/unternehmen\/schaaf_deutschland-768x530.jpg 768w, https:\/\/www.schaaf-gmbh.com\/wp-content\/uploads\/unternehmen\/schaaf_deutschland-640x442.jpg 640w, https:\/\/www.schaaf-gmbh.com\/wp-content\/uploads\/unternehmen\/schaaf_deutschland-400x276.jpg 400w, https:\/\/www.schaaf-gmbh.com\/wp-content\/uploads\/unternehmen\/schaaf_deutschland-367x253.jpg 367w\">\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-171b0b34 elementor-widget elementor-widget-heading\" data-id=\"171b0b34\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><a href=\"\/de\/unternehmen\/\">Unternehmen<\/a><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/section>\r\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/section>\r\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Ansprechpartner Chinesisch Chinesischsprachige Mitarbeiter Yong Yan kfm. Abteilung yong.yan@schaaf-gmbh.com +49-2431-97770-17 +49-2431-97770-71<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":17399,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-20490","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.6 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Ansprechpartner Chinesisch - SCHAAF - Leading joining technology<\/title>\n<meta name=\"description\" content=\"Die chinesischsprachigen Ansprechpartner von SCHAAF helfen Ihnen gerne weiter. Die Kontaktdaten finden Sie hier.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.schaaf-gmbh.com\/de\/kontakt\/deutschland\/ansprechpartner-sprachen\/chinesisch\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ansprechpartner Chinesisch\" \/>\n<meta property=\"og:description\" content=\"Die chinesischsprachigen Ansprechpartner von SCHAAF helfen Ihnen gerne weiter. Die Kontaktdaten finden Sie hier.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.schaaf-gmbh.com\/de\/kontakt\/deutschland\/ansprechpartner-sprachen\/chinesisch\/\" \/>\n<meta property=\"og:site_name\" content=\"SCHAAF - Leading joining technology\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Schaaf.gmbh.de\/\" \/>\n<meta property=\"article:modified_time\" content=\"2023-04-25T08:22:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.schaaf-gmbh.com\/wp-content\/uploads\/mitarbeiter\/schaaf_mitarbeiter_yan-yong-250x350.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.schaaf-gmbh.com\\\/de\\\/kontakt\\\/deutschland\\\/ansprechpartner-sprachen\\\/chinesisch\\\/\",\"url\":\"https:\\\/\\\/www.schaaf-gmbh.com\\\/de\\\/kontakt\\\/deutschland\\\/ansprechpartner-sprachen\\\/chinesisch\\\/\",\"name\":\"Ansprechpartner Chinesisch - SCHAAF - Leading joining technology\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.schaaf-gmbh.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.schaaf-gmbh.com\\\/de\\\/kontakt\\\/deutschland\\\/ansprechpartner-sprachen\\\/chinesisch\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.schaaf-gmbh.com\\\/de\\\/kontakt\\\/deutschland\\\/ansprechpartner-sprachen\\\/chinesisch\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.schaaf-gmbh.com\\\/wp-content\\\/uploads\\\/mitarbeiter\\\/schaaf_mitarbeiter_yan-yong-250x350.jpg\",\"datePublished\":\"2021-08-11T14:42:04+00:00\",\"dateModified\":\"2023-04-25T08:22:37+00:00\",\"description\":\"Die chinesischsprachigen Ansprechpartner von SCHAAF helfen Ihnen gerne weiter. Die Kontaktdaten finden Sie hier.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.schaaf-gmbh.com\\\/de\\\/kontakt\\\/deutschland\\\/ansprechpartner-sprachen\\\/chinesisch\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.schaaf-gmbh.com\\\/de\\\/kontakt\\\/deutschland\\\/ansprechpartner-sprachen\\\/chinesisch\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.schaaf-gmbh.com\\\/de\\\/kontakt\\\/deutschland\\\/ansprechpartner-sprachen\\\/chinesisch\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.schaaf-gmbh.com\\\/wp-content\\\/uploads\\\/mitarbeiter\\\/schaaf_mitarbeiter_yan-yong-250x350.jpg\",\"contentUrl\":\"https:\\\/\\\/www.schaaf-gmbh.com\\\/wp-content\\\/uploads\\\/mitarbeiter\\\/schaaf_mitarbeiter_yan-yong-250x350.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.schaaf-gmbh.com\\\/de\\\/kontakt\\\/deutschland\\\/ansprechpartner-sprachen\\\/chinesisch\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.schaaf-gmbh.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Kontakt\",\"item\":\"https:\\\/\\\/www.schaaf-gmbh.com\\\/de\\\/kontakt\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Ansprechpartner \u00dcbersicht\",\"item\":\"https:\\\/\\\/www.schaaf-gmbh.com\\\/de\\\/kontakt\\\/deutschland\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Ansprechpartner Sprachen\",\"item\":\"https:\\\/\\\/www.schaaf-gmbh.com\\\/de\\\/kontakt\\\/deutschland\\\/ansprechpartner-sprachen\\\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"Ansprechpartner Chinesisch\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.schaaf-gmbh.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/www.schaaf-gmbh.com\\\/de\\\/\",\"name\":\"SCHAAF - Leading joining technology\",\"description\":\"Leading joining technology\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.schaaf-gmbh.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.schaaf-gmbh.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.schaaf-gmbh.com\\\/de\\\/#organization\",\"name\":\"Schaaf GmbH & Co. KG\",\"alternateName\":\"SCHAAF GmbH & Co. KG\",\"url\":\"https:\\\/\\\/www.schaaf-gmbh.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.schaaf-gmbh.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.schaaf-gmbh.com\\\/wp-content\\\/uploads\\\/grundaufbau\\\/apple_176x176.png\",\"contentUrl\":\"https:\\\/\\\/www.schaaf-gmbh.com\\\/wp-content\\\/uploads\\\/grundaufbau\\\/apple_176x176.png\",\"width\":176,\"height\":176,\"caption\":\"Schaaf GmbH & Co. KG\"},\"image\":{\"@id\":\"https:\\\/\\\/www.schaaf-gmbh.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Schaaf.gmbh.de\\\/\",\"https:\\\/\\\/www.instagram.com\\\/schaaf.gmbh\\\/\",\"https:\\\/\\\/de.linkedin.com\\\/company\\\/schaaf-gmbh-com\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCJfkln8LVDeGgV-V8yzePBQ\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Ansprechpartner Chinesisch - SCHAAF - Leading joining technology","description":"Die chinesischsprachigen Ansprechpartner von SCHAAF helfen Ihnen gerne weiter. Die Kontaktdaten finden Sie hier.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.schaaf-gmbh.com\/de\/kontakt\/deutschland\/ansprechpartner-sprachen\/chinesisch\/","og_locale":"de_DE","og_type":"article","og_title":"Ansprechpartner Chinesisch","og_description":"Die chinesischsprachigen Ansprechpartner von SCHAAF helfen Ihnen gerne weiter. Die Kontaktdaten finden Sie hier.","og_url":"https:\/\/www.schaaf-gmbh.com\/de\/kontakt\/deutschland\/ansprechpartner-sprachen\/chinesisch\/","og_site_name":"SCHAAF - Leading joining technology","article_publisher":"https:\/\/www.facebook.com\/Schaaf.gmbh.de\/","article_modified_time":"2023-04-25T08:22:37+00:00","og_image":[{"url":"https:\/\/www.schaaf-gmbh.com\/wp-content\/uploads\/mitarbeiter\/schaaf_mitarbeiter_yan-yong-250x350.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.schaaf-gmbh.com\/de\/kontakt\/deutschland\/ansprechpartner-sprachen\/chinesisch\/","url":"https:\/\/www.schaaf-gmbh.com\/de\/kontakt\/deutschland\/ansprechpartner-sprachen\/chinesisch\/","name":"Ansprechpartner Chinesisch - SCHAAF - Leading joining technology","isPartOf":{"@id":"https:\/\/www.schaaf-gmbh.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.schaaf-gmbh.com\/de\/kontakt\/deutschland\/ansprechpartner-sprachen\/chinesisch\/#primaryimage"},"image":{"@id":"https:\/\/www.schaaf-gmbh.com\/de\/kontakt\/deutschland\/ansprechpartner-sprachen\/chinesisch\/#primaryimage"},"thumbnailUrl":"https:\/\/www.schaaf-gmbh.com\/wp-content\/uploads\/mitarbeiter\/schaaf_mitarbeiter_yan-yong-250x350.jpg","datePublished":"2021-08-11T14:42:04+00:00","dateModified":"2023-04-25T08:22:37+00:00","description":"Die chinesischsprachigen Ansprechpartner von SCHAAF helfen Ihnen gerne weiter. Die Kontaktdaten finden Sie hier.","breadcrumb":{"@id":"https:\/\/www.schaaf-gmbh.com\/de\/kontakt\/deutschland\/ansprechpartner-sprachen\/chinesisch\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.schaaf-gmbh.com\/de\/kontakt\/deutschland\/ansprechpartner-sprachen\/chinesisch\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.schaaf-gmbh.com\/de\/kontakt\/deutschland\/ansprechpartner-sprachen\/chinesisch\/#primaryimage","url":"https:\/\/www.schaaf-gmbh.com\/wp-content\/uploads\/mitarbeiter\/schaaf_mitarbeiter_yan-yong-250x350.jpg","contentUrl":"https:\/\/www.schaaf-gmbh.com\/wp-content\/uploads\/mitarbeiter\/schaaf_mitarbeiter_yan-yong-250x350.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.schaaf-gmbh.com\/de\/kontakt\/deutschland\/ansprechpartner-sprachen\/chinesisch\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.schaaf-gmbh.com\/de\/"},{"@type":"ListItem","position":2,"name":"Kontakt","item":"https:\/\/www.schaaf-gmbh.com\/de\/kontakt\/"},{"@type":"ListItem","position":3,"name":"Ansprechpartner \u00dcbersicht","item":"https:\/\/www.schaaf-gmbh.com\/de\/kontakt\/deutschland\/"},{"@type":"ListItem","position":4,"name":"Ansprechpartner Sprachen","item":"https:\/\/www.schaaf-gmbh.com\/de\/kontakt\/deutschland\/ansprechpartner-sprachen\/"},{"@type":"ListItem","position":5,"name":"Ansprechpartner Chinesisch"}]},{"@type":"WebSite","@id":"https:\/\/www.schaaf-gmbh.com\/de\/#website","url":"https:\/\/www.schaaf-gmbh.com\/de\/","name":"SCHAAF - Leading joining technology","description":"Leading joining technology","publisher":{"@id":"https:\/\/www.schaaf-gmbh.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.schaaf-gmbh.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.schaaf-gmbh.com\/de\/#organization","name":"Schaaf GmbH & Co. KG","alternateName":"SCHAAF GmbH & Co. KG","url":"https:\/\/www.schaaf-gmbh.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.schaaf-gmbh.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/www.schaaf-gmbh.com\/wp-content\/uploads\/grundaufbau\/apple_176x176.png","contentUrl":"https:\/\/www.schaaf-gmbh.com\/wp-content\/uploads\/grundaufbau\/apple_176x176.png","width":176,"height":176,"caption":"Schaaf GmbH & Co. KG"},"image":{"@id":"https:\/\/www.schaaf-gmbh.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Schaaf.gmbh.de\/","https:\/\/www.instagram.com\/schaaf.gmbh\/","https:\/\/de.linkedin.com\/company\/schaaf-gmbh-com","https:\/\/www.youtube.com\/channel\/UCJfkln8LVDeGgV-V8yzePBQ"]}]}},"_links":{"self":[{"href":"https:\/\/www.schaaf-gmbh.com\/de\/wp-json\/wp\/v2\/pages\/20490","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.schaaf-gmbh.com\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.schaaf-gmbh.com\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.schaaf-gmbh.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.schaaf-gmbh.com\/de\/wp-json\/wp\/v2\/comments?post=20490"}],"version-history":[{"count":1,"href":"https:\/\/www.schaaf-gmbh.com\/de\/wp-json\/wp\/v2\/pages\/20490\/revisions"}],"predecessor-version":[{"id":58210,"href":"https:\/\/www.schaaf-gmbh.com\/de\/wp-json\/wp\/v2\/pages\/20490\/revisions\/58210"}],"up":[{"embeddable":true,"href":"https:\/\/www.schaaf-gmbh.com\/de\/wp-json\/wp\/v2\/pages\/17399"}],"wp:attachment":[{"href":"https:\/\/www.schaaf-gmbh.com\/de\/wp-json\/wp\/v2\/media?parent=20490"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}