{"id":58967,"date":"2023-08-30T14:38:25","date_gmt":"2023-08-30T14:38:25","guid":{"rendered":"https:\/\/www.schaaf-gmbh.com\/exhibition-in-september-2023\/"},"modified":"2023-08-30T14:50:14","modified_gmt":"2023-08-30T14:50:14","slug":"messe-im-september-2023","status":"publish","type":"post","link":"https:\/\/www.schaaf-gmbh.com\/en\/messe-im-september-2023\/","title":{"rendered":"Exhibition in September 2023"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"58967\" class=\"elementor elementor-58967 elementor-58954\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2be6c35c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2be6c35c\" data-element_type=\"section\" data-e-type=\"section\">\r\n\t\t\r\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-114f8405\" data-id=\"114f8405\" data-element_type=\"column\" data-e-type=\"column\">\r\n\t\t\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\r\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-717e7b6 elementor-widget elementor-widget-image\" data-id=\"717e7b6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"710\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" class=\"attachment-large size-large wp-image-58958 lazyload\" alt=\"HUSUM WIND 2023, 12. \u2013 15. September, Halle 4, Stand B16\" sizes=\"(max-width: 1024px) 100vw, 1024px\" data-src=\"https:\/\/www.schaaf-gmbh.com\/wp-content\/uploads\/aktuelles\/aktuelles_messe_husumwind_2023.jpg\" data-srcset=\"https:\/\/www.schaaf-gmbh.com\/wp-content\/uploads\/aktuelles\/aktuelles_messe_husumwind_2023.jpg 1024w, https:\/\/www.schaaf-gmbh.com\/wp-content\/uploads\/aktuelles\/aktuelles_messe_husumwind_2023-768x533.jpg 768w\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bee0d61 elementor-widget elementor-widget-heading\" data-id=\"bee0d61\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">HUSUM WIND 2023, 12 \u2013 15 September, Hall 4, stall B16<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-33319e25 elementor-widget elementor-widget-text-editor\" data-id=\"33319e25\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tWe look forward to presenting the latest developments in fastening technology to you at this year&#8217;s HUSUM WIND.\r\n\r\nBe excited about the best possible connection solutions in the matter of tower-, foundation, nacelle- and blade bolting as well as connections for the drive train elements. For all the connection solutions, we are capable to provide a detailed documentation about the pre-tensioning forces.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/section>\r\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>HUSUM WIND 2023, 12 \u2013 15 September, Hall 4, stall B16<\/p>\n","protected":false},"author":1,"featured_media":58958,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[133,380],"tags":[427,406,426],"class_list":["post-58967","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aktuelles","category-news","tag-exhibitions","tag-husum-wind-en","tag-windenergy-en"],"featured_image_src":{"landsacpe":["https:\/\/www.schaaf-gmbh.com\/wp-content\/uploads\/aktuelles\/aktuelles_messe_husumwind_2023.jpg",1024,710,false],"list":["https:\/\/www.schaaf-gmbh.com\/wp-content\/uploads\/aktuelles\/aktuelles_messe_husumwind_2023.jpg",1024,710,false],"medium":["https:\/\/www.schaaf-gmbh.com\/wp-content\/uploads\/aktuelles\/aktuelles_messe_husumwind_2023-300x208.jpg",300,208,true],"full":["https:\/\/www.schaaf-gmbh.com\/wp-content\/uploads\/aktuelles\/aktuelles_messe_husumwind_2023.jpg",1024,710,false]},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.6 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Exhibition in September 2023 - SCHAAF - Leading joining technology<\/title>\n<meta name=\"description\" content=\"We look forward to presenting the latest developments in fastening technology to you at this year&#039;s HUSUM WIND.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.schaaf-gmbh.com\/en\/messe-im-september-2023\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Exhibition in September 2023\" \/>\n<meta property=\"og:description\" content=\"We look forward to presenting the latest developments in fastening technology to you at this year&#039;s HUSUM WIND.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.schaaf-gmbh.com\/en\/messe-im-september-2023\/\" \/>\n<meta property=\"og:site_name\" content=\"SCHAAF - Leading joining technology\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Schaaf.gmbh.de\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-08-30T14:38:25+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-08-30T14:50:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.schaaf-gmbh.com\/wp-content\/uploads\/aktuelles\/aktuelles_messe_husumwind_2023.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"710\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"sgeissler\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"sgeissler\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.schaaf-gmbh.com\\\/en\\\/messe-im-september-2023\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.schaaf-gmbh.com\\\/en\\\/messe-im-september-2023\\\/\"},\"author\":{\"name\":\"sgeissler\",\"@id\":\"https:\\\/\\\/www.schaaf-gmbh.com\\\/en\\\/#\\\/schema\\\/person\\\/dfbb7c591f1045bdb729e8d574e9d458\"},\"headline\":\"Exhibition in September 2023\",\"datePublished\":\"2023-08-30T14:38:25+00:00\",\"dateModified\":\"2023-08-30T14:50:14+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.schaaf-gmbh.com\\\/en\\\/messe-im-september-2023\\\/\"},\"wordCount\":72,\"publisher\":{\"@id\":\"https:\\\/\\\/www.schaaf-gmbh.com\\\/en\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.schaaf-gmbh.com\\\/en\\\/messe-im-september-2023\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.schaaf-gmbh.com\\\/wp-content\\\/uploads\\\/aktuelles\\\/aktuelles_messe_husumwind_2023.jpg\",\"keywords\":[\"Exhibitions\",\"HUSUM WIND\",\"Windenergy\"],\"articleSection\":[\"Aktuelles\",\"News\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.schaaf-gmbh.com\\\/en\\\/messe-im-september-2023\\\/\",\"url\":\"https:\\\/\\\/www.schaaf-gmbh.com\\\/en\\\/messe-im-september-2023\\\/\",\"name\":\"Exhibition in September 2023 - SCHAAF - Leading joining technology\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.schaaf-gmbh.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.schaaf-gmbh.com\\\/en\\\/messe-im-september-2023\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.schaaf-gmbh.com\\\/en\\\/messe-im-september-2023\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.schaaf-gmbh.com\\\/wp-content\\\/uploads\\\/aktuelles\\\/aktuelles_messe_husumwind_2023.jpg\",\"datePublished\":\"2023-08-30T14:38:25+00:00\",\"dateModified\":\"2023-08-30T14:50:14+00:00\",\"description\":\"We look forward to presenting the latest developments in fastening technology to you at this year's HUSUM WIND.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.schaaf-gmbh.com\\\/en\\\/messe-im-september-2023\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.schaaf-gmbh.com\\\/en\\\/messe-im-september-2023\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.schaaf-gmbh.com\\\/en\\\/messe-im-september-2023\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.schaaf-gmbh.com\\\/wp-content\\\/uploads\\\/aktuelles\\\/aktuelles_messe_husumwind_2023.jpg\",\"contentUrl\":\"https:\\\/\\\/www.schaaf-gmbh.com\\\/wp-content\\\/uploads\\\/aktuelles\\\/aktuelles_messe_husumwind_2023.jpg\",\"width\":1024,\"height\":710,\"caption\":\"HUSUM WIND 2023, 12. \u2013 15. September, Halle 4, Stand B16\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.schaaf-gmbh.com\\\/en\\\/messe-im-september-2023\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.schaaf-gmbh.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Exhibition in September 2023\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.schaaf-gmbh.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.schaaf-gmbh.com\\\/en\\\/\",\"name\":\"SCHAAF - Leading joining technology\",\"description\":\"Hydraulic High-Pressure\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.schaaf-gmbh.com\\\/en\\\/#organization\"},\"alternateName\":\"SCHAAF GmbH & Co. KG\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.schaaf-gmbh.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.schaaf-gmbh.com\\\/en\\\/#organization\",\"name\":\"Schaaf GmbH & Co. KG\",\"alternateName\":\"SCHAAF GmbH & Co. KG\",\"url\":\"https:\\\/\\\/www.schaaf-gmbh.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.schaaf-gmbh.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.schaaf-gmbh.com\\\/wp-content\\\/uploads\\\/grundaufbau\\\/apple_176x176.png\",\"contentUrl\":\"https:\\\/\\\/www.schaaf-gmbh.com\\\/wp-content\\\/uploads\\\/grundaufbau\\\/apple_176x176.png\",\"width\":176,\"height\":176,\"caption\":\"Schaaf GmbH & Co. KG\"},\"image\":{\"@id\":\"https:\\\/\\\/www.schaaf-gmbh.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Schaaf.gmbh.de\\\/\",\"https:\\\/\\\/www.instagram.com\\\/schaaf.gmbh\\\/\",\"https:\\\/\\\/de.linkedin.com\\\/company\\\/schaaf-gmbh-com\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCJfkln8LVDeGgV-V8yzePBQ\"],\"slogan\":\"Leading joining technology\",\"address\":{\"@type\":\"PostalAddress\",\"streetAddress\":\"Br\u00fcsseler Allee 22\",\"postalCode\":\"41812\",\"addressLocality\":\"Erkelenz\",\"addressRegion\":\"Nordrhein-Westfalen\",\"addressCountry\":\"DE\"},\"areaServed\":{\"@type\":\"Place\",\"name\":\"Worldwide\"},\"contactPoint\":[{\"@type\":\"ContactPoint\",\"contactType\":\"general inquiries\",\"telephone\":\"+49-2431-97770-0\",\"email\":\"info@schaaf-gmbh.com\",\"areaServed\":\"Worldwide\",\"availableLanguage\":[{\"@type\":\"Language\",\"name\":\"Deutsch\",\"alternateName\":\"de\"},{\"@type\":\"Language\",\"name\":\"English\",\"alternateName\":\"en\"},{\"@type\":\"Language\",\"name\":\"Fran\u00e7ais\",\"alternateName\":\"fr\"},{\"@type\":\"Language\",\"name\":\"Espa\u00f1ol\",\"alternateName\":\"es\"},{\"@type\":\"Language\",\"name\":\"\u4e2d\u6587\",\"alternateName\":\"zh\"},{\"@type\":\"Language\",\"name\":\"\u0420\u0443\u0441\u0441\u043a\u0438\u0439\",\"alternateName\":\"ru\"}]}],\"knowsAbout\":[\"Verbindungstechnik\",\"Schraubenspannvorrichtungen\",\"Hydraulikmuttern\",\"Hydraulische Hochdruckwerkzeuge\",\"Bolt Tensioning\",\"Flanschverbindungen\",\"Industrielle Schraubverbindungen\",\"Verbindungsbolzen\",\"Wellen- und Achsverbindungen\",\"ExpaTen\",\"GripLoc\",\"GripCon\",\"TTG-Technologie\"],\"hasCredential\":[{\"@type\":\"EducationalOccupationalCredential\",\"credentialCategory\":\"Certification\",\"name\":\"DIN EN ISO 9001:2015\"}],\"description\":\"Die SCHAAF GmbH & Co. KG entwickelt und fertigt seit 1954 Verbindungstechnik sowie hydraulische Hochdruckwerkzeuge f\u00fcr industrielle Anwendungen weltweit. Zum Produktspektrum geh\u00f6ren Schraubenspannvorrichtungen, Hydraulikmuttern, ExpaTen, GripLoc, GripCon, Verbindungsbolzen und die patentierte TTG-Technologie. Die L\u00f6sungen kommen unter anderem im Maschinenbau, in der Windenergie, im Schiffbau sowie in der Energie- und Prozessindustrie zum Einsatz.\",\"email\":\"info@schaaf-gmbh.com\",\"telephone\":\"+49 \u2013 24 31 \u2013 9 77 70-0\",\"legalName\":\"Schaaf GmbH & Co. KG\",\"foundingDate\":\"1954-01-01\",\"vatID\":\"DE 814 64 67 52\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"201\",\"maxValue\":\"500\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.schaaf-gmbh.com\\\/en\\\/#\\\/schema\\\/person\\\/dfbb7c591f1045bdb729e8d574e9d458\",\"name\":\"sgeissler\",\"sameAs\":[\"https:\\\/\\\/www.schaaf-gmbh.com\"],\"url\":\"https:\\\/\\\/www.schaaf-gmbh.com\\\/en\\\/author\\\/sgeissler\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Exhibition in September 2023 - SCHAAF - Leading joining technology","description":"We look forward to presenting the latest developments in fastening technology to you at this year's HUSUM WIND.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.schaaf-gmbh.com\/en\/messe-im-september-2023\/","og_locale":"en_US","og_type":"article","og_title":"Exhibition in September 2023","og_description":"We look forward to presenting the latest developments in fastening technology to you at this year's HUSUM WIND.","og_url":"https:\/\/www.schaaf-gmbh.com\/en\/messe-im-september-2023\/","og_site_name":"SCHAAF - Leading joining technology","article_publisher":"https:\/\/www.facebook.com\/Schaaf.gmbh.de\/","article_published_time":"2023-08-30T14:38:25+00:00","article_modified_time":"2023-08-30T14:50:14+00:00","og_image":[{"width":1024,"height":710,"url":"https:\/\/www.schaaf-gmbh.com\/wp-content\/uploads\/aktuelles\/aktuelles_messe_husumwind_2023.jpg","type":"image\/jpeg"}],"author":"sgeissler","twitter_card":"summary_large_image","twitter_misc":{"Written by":"sgeissler","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.schaaf-gmbh.com\/en\/messe-im-september-2023\/#article","isPartOf":{"@id":"https:\/\/www.schaaf-gmbh.com\/en\/messe-im-september-2023\/"},"author":{"name":"sgeissler","@id":"https:\/\/www.schaaf-gmbh.com\/en\/#\/schema\/person\/dfbb7c591f1045bdb729e8d574e9d458"},"headline":"Exhibition in September 2023","datePublished":"2023-08-30T14:38:25+00:00","dateModified":"2023-08-30T14:50:14+00:00","mainEntityOfPage":{"@id":"https:\/\/www.schaaf-gmbh.com\/en\/messe-im-september-2023\/"},"wordCount":72,"publisher":{"@id":"https:\/\/www.schaaf-gmbh.com\/en\/#organization"},"image":{"@id":"https:\/\/www.schaaf-gmbh.com\/en\/messe-im-september-2023\/#primaryimage"},"thumbnailUrl":"https:\/\/www.schaaf-gmbh.com\/wp-content\/uploads\/aktuelles\/aktuelles_messe_husumwind_2023.jpg","keywords":["Exhibitions","HUSUM WIND","Windenergy"],"articleSection":["Aktuelles","News"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/www.schaaf-gmbh.com\/en\/messe-im-september-2023\/","url":"https:\/\/www.schaaf-gmbh.com\/en\/messe-im-september-2023\/","name":"Exhibition in September 2023 - SCHAAF - Leading joining technology","isPartOf":{"@id":"https:\/\/www.schaaf-gmbh.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.schaaf-gmbh.com\/en\/messe-im-september-2023\/#primaryimage"},"image":{"@id":"https:\/\/www.schaaf-gmbh.com\/en\/messe-im-september-2023\/#primaryimage"},"thumbnailUrl":"https:\/\/www.schaaf-gmbh.com\/wp-content\/uploads\/aktuelles\/aktuelles_messe_husumwind_2023.jpg","datePublished":"2023-08-30T14:38:25+00:00","dateModified":"2023-08-30T14:50:14+00:00","description":"We look forward to presenting the latest developments in fastening technology to you at this year's HUSUM WIND.","breadcrumb":{"@id":"https:\/\/www.schaaf-gmbh.com\/en\/messe-im-september-2023\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.schaaf-gmbh.com\/en\/messe-im-september-2023\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.schaaf-gmbh.com\/en\/messe-im-september-2023\/#primaryimage","url":"https:\/\/www.schaaf-gmbh.com\/wp-content\/uploads\/aktuelles\/aktuelles_messe_husumwind_2023.jpg","contentUrl":"https:\/\/www.schaaf-gmbh.com\/wp-content\/uploads\/aktuelles\/aktuelles_messe_husumwind_2023.jpg","width":1024,"height":710,"caption":"HUSUM WIND 2023, 12. \u2013 15. September, Halle 4, Stand B16"},{"@type":"BreadcrumbList","@id":"https:\/\/www.schaaf-gmbh.com\/en\/messe-im-september-2023\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.schaaf-gmbh.com\/en\/"},{"@type":"ListItem","position":2,"name":"Exhibition in September 2023"}]},{"@type":"WebSite","@id":"https:\/\/www.schaaf-gmbh.com\/en\/#website","url":"https:\/\/www.schaaf-gmbh.com\/en\/","name":"SCHAAF - Leading joining technology","description":"Hydraulic High-Pressure","publisher":{"@id":"https:\/\/www.schaaf-gmbh.com\/en\/#organization"},"alternateName":"SCHAAF GmbH & Co. KG","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.schaaf-gmbh.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.schaaf-gmbh.com\/en\/#organization","name":"Schaaf GmbH & Co. KG","alternateName":"SCHAAF GmbH & Co. KG","url":"https:\/\/www.schaaf-gmbh.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.schaaf-gmbh.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.schaaf-gmbh.com\/wp-content\/uploads\/grundaufbau\/apple_176x176.png","contentUrl":"https:\/\/www.schaaf-gmbh.com\/wp-content\/uploads\/grundaufbau\/apple_176x176.png","width":176,"height":176,"caption":"Schaaf GmbH & Co. KG"},"image":{"@id":"https:\/\/www.schaaf-gmbh.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Schaaf.gmbh.de\/","https:\/\/www.instagram.com\/schaaf.gmbh\/","https:\/\/de.linkedin.com\/company\/schaaf-gmbh-com","https:\/\/www.youtube.com\/channel\/UCJfkln8LVDeGgV-V8yzePBQ"],"slogan":"Leading joining technology","address":{"@type":"PostalAddress","streetAddress":"Br\u00fcsseler Allee 22","postalCode":"41812","addressLocality":"Erkelenz","addressRegion":"Nordrhein-Westfalen","addressCountry":"DE"},"areaServed":{"@type":"Place","name":"Worldwide"},"contactPoint":[{"@type":"ContactPoint","contactType":"general inquiries","telephone":"+49-2431-97770-0","email":"info@schaaf-gmbh.com","areaServed":"Worldwide","availableLanguage":[{"@type":"Language","name":"Deutsch","alternateName":"de"},{"@type":"Language","name":"English","alternateName":"en"},{"@type":"Language","name":"Fran\u00e7ais","alternateName":"fr"},{"@type":"Language","name":"Espa\u00f1ol","alternateName":"es"},{"@type":"Language","name":"\u4e2d\u6587","alternateName":"zh"},{"@type":"Language","name":"\u0420\u0443\u0441\u0441\u043a\u0438\u0439","alternateName":"ru"}]}],"knowsAbout":["Verbindungstechnik","Schraubenspannvorrichtungen","Hydraulikmuttern","Hydraulische Hochdruckwerkzeuge","Bolt Tensioning","Flanschverbindungen","Industrielle Schraubverbindungen","Verbindungsbolzen","Wellen- und Achsverbindungen","ExpaTen","GripLoc","GripCon","TTG-Technologie"],"hasCredential":[{"@type":"EducationalOccupationalCredential","credentialCategory":"Certification","name":"DIN EN ISO 9001:2015"}],"description":"Die SCHAAF GmbH & Co. KG entwickelt und fertigt seit 1954 Verbindungstechnik sowie hydraulische Hochdruckwerkzeuge f\u00fcr industrielle Anwendungen weltweit. Zum Produktspektrum geh\u00f6ren Schraubenspannvorrichtungen, Hydraulikmuttern, ExpaTen, GripLoc, GripCon, Verbindungsbolzen und die patentierte TTG-Technologie. Die L\u00f6sungen kommen unter anderem im Maschinenbau, in der Windenergie, im Schiffbau sowie in der Energie- und Prozessindustrie zum Einsatz.","email":"info@schaaf-gmbh.com","telephone":"+49 \u2013 24 31 \u2013 9 77 70-0","legalName":"Schaaf GmbH & Co. KG","foundingDate":"1954-01-01","vatID":"DE 814 64 67 52","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"201","maxValue":"500"}},{"@type":"Person","@id":"https:\/\/www.schaaf-gmbh.com\/en\/#\/schema\/person\/dfbb7c591f1045bdb729e8d574e9d458","name":"sgeissler","sameAs":["https:\/\/www.schaaf-gmbh.com"],"url":"https:\/\/www.schaaf-gmbh.com\/en\/author\/sgeissler\/"}]}},"_links":{"self":[{"href":"https:\/\/www.schaaf-gmbh.com\/en\/wp-json\/wp\/v2\/posts\/58967","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.schaaf-gmbh.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.schaaf-gmbh.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.schaaf-gmbh.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.schaaf-gmbh.com\/en\/wp-json\/wp\/v2\/comments?post=58967"}],"version-history":[{"count":2,"href":"https:\/\/www.schaaf-gmbh.com\/en\/wp-json\/wp\/v2\/posts\/58967\/revisions"}],"predecessor-version":[{"id":58977,"href":"https:\/\/www.schaaf-gmbh.com\/en\/wp-json\/wp\/v2\/posts\/58967\/revisions\/58977"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.schaaf-gmbh.com\/en\/wp-json\/wp\/v2\/media\/58958"}],"wp:attachment":[{"href":"https:\/\/www.schaaf-gmbh.com\/en\/wp-json\/wp\/v2\/media?parent=58967"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.schaaf-gmbh.com\/en\/wp-json\/wp\/v2\/categories?post=58967"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.schaaf-gmbh.com\/en\/wp-json\/wp\/v2\/tags?post=58967"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}