{"id":34743,"date":"2021-08-05T12:10:37","date_gmt":"2021-08-05T12:10:37","guid":{"rendered":"https:\/\/www.schaaf-gmbh.com\/hm-pg12"},"modified":"2024-11-18T13:33:58","modified_gmt":"2024-11-18T13:33:58","slug":"hm-pg12","status":"publish","type":"page","link":"https:\/\/www.schaaf-gmbh.com\/fr\/elements-dassemblage\/hydraulikmutter\/hm-pg12\/","title":{"rendered":"Ecrou hydraulique HM PG12"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"34743\" class=\"elementor elementor-34743 elementor-17454\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-eef2d11 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"eef2d11\" data-element_type=\"section\" data-e-type=\"section\">\r\n\t\t\r\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-bcd2a41\" data-id=\"bcd2a41\" data-element_type=\"column\" data-e-type=\"column\">\r\n\t\t\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\r\n\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-625fbd4 col-sm-12 col-12 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"625fbd4\" data-element_type=\"section\" data-e-type=\"section\">\r\n\t\t\r\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-414ec49 col-sm-3 col-6\" data-id=\"414ec49\" data-element_type=\"column\" data-e-type=\"column\">\r\n\t\t\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\r\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-626e408 elementor-widget elementor-widget-image\" data-id=\"626e408\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"300\" height=\"330\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" class=\"attachment-large size-large wp-image-8714 lazyload\" alt=\"Icon PG12\" data-src=\"https:\/\/www.schaaf-gmbh.com\/wp-content\/uploads\/produkte\/piktogramme-pg\/pg12.png\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-1f335e7 col-sm-3 col-6\" data-id=\"1f335e7\" data-element_type=\"column\" data-e-type=\"column\">\r\n\t\t\t\t\t<div class=\"elementor-widget-wrap\">\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-50be3c5 col-sm-3 col-6\" data-id=\"50be3c5\" data-element_type=\"column\" data-e-type=\"column\">\r\n\t\t\t\t\t<div class=\"elementor-widget-wrap\">\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-ab97a9c col-sm-3 col-6\" data-id=\"ab97a9c\" data-element_type=\"column\" data-e-type=\"column\">\r\n\t\t\t\t\t<div class=\"elementor-widget-wrap\">\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/section>\r\n\t\t\t\t<div class=\"elementor-element elementor-element-c1dae74 elementor-widget elementor-widget-heading\" data-id=\"c1dae74\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Ecrou hydraulique PG12<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-421f346 elementor-widget elementor-widget-heading\" data-id=\"421f346\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\"><h4 class=\"elementor-heading-title elementor-size-default\" style=\"font-family: var( --e-global-typography-primary-font-family ), Arial, Helvetica, sans-serif;font-weight: var( --e-global-typography-primary-font-weight );white-space: normal\">Tensionnement axial de boulons par un systeme hydraulique de haute pression<br><\/h4><span style=\"font-family: var( --e-global-typography-primary-font-family ), Arial, Helvetica, sans-serif;font-weight: var( --e-global-typography-primary-font-weight );letter-spacing: -0.05em;white-space: normal\">R\u00e9duction des co\u00fbts - Puissant - R\u00e9utilisable<\/span><\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-38cb88b elementor-widget elementor-widget-text-editor\" data-id=\"38cb88b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tLes \u00e9crous hydrauliques ne n\u00e9cessitent pas de projection de filetage comme les tendeurs de boulons, ce qui permet leur utilisation dans des constructions anciennes pour remplacer les connexions \u00e0 boulon serr\u00e9es avec cl\u00e9 dynamom\u00e9trique. Pour les grandes connexions de boulons en particulier, cela facilite le travail et augmente la s\u00e9curit\u00e9 de la force de tension. Compar\u00e9s aux tendeurs de boulons, les \u00e9crous hydrauliques permettent des temps de changement plus rapides pour les connexions qui n\u00e9cessitent un serrage et un desserrage r\u00e9guliers. Cela acc\u00e9l\u00e8re la v\u00e9rification des forces de charge.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-678ec53 elementor-widget elementor-widget-text-editor\" data-id=\"678ec53\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tLa caract\u00e9ristique distinctive des \u00e9crous hydrauliques du groupe de produits 12 est que la force de pr\u00e9-tension axiale est g\u00e9n\u00e9r\u00e9e par un piston diff\u00e9rentiel et est maintenue par un \u00e9crou de verrouillage int\u00e9gr\u00e9, permettant ainsi la lib\u00e9ration de la pression hydraulique.\r\n<ul class=\"liste\">\r\n \t<li>Simple \u00e9tage<\/li>\r\n \t<li>Mise en contrainte axiale uniquement<\/li>\r\n \t<li>Ecrou m\u00e9canique de blocage<\/li>\r\n<\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3c0d11d elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"3c0d11d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-aeff01f\" data-id=\"aeff01f\" data-element_type=\"column\" data-e-type=\"column\">\r\n\t\t\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\r\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1f49952 elementor-widget__width-initial elementor-widget elementor-widget-beaf-slider\" data-id=\"1f49952\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"beaf-slider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\n\t\t\t\n\t<style type=\"text\/css\">\n\t\t.slider-info-57749.bafg-slider-info .bafg-slider-title {\n\t\t\t\t\t\t\tfont-size:\n\t\t\t\t\t22px\t\t\t\t;\n\t\t\t\n\t\t\t\n\t\t\t\t\t}\n\n\t\t.slider-info-57749.bafg-slider-info .bafg-slider-description {\n\t\t\t\n\t\t\t\n\t\t\t\t\t}\n\t\t\n\t\t\n\t\t.slider-info-57749.bafg-slider-info .bafg_slider_readmore_button {\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\ttext-align: center;\n\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\t\t}\n\n\t\t.slider-info-57749.bafg-slider-info .bafg_slider_readmore_button:hover {\n\n\t\t\t\n\t\t\t\n\t\t\t\t\t}\n\t<\/style>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t<div style=\"\t\t\t\t\t\t \t\t\t\t\t\t \t\t\t\t\t\t   float: right; width: 100%;\t\t\t\t\t\t\"\n\t\t\t\t\t\t\tclass=\"bafg-twentytwenty-container   slider-57749 default  \"\n\t\t\t\t\t\t\tdata-label_outside=\"\"\n\t\t\t\t\t\t\tbafg-orientation=\"horizontal\" bafg-default-offset=\"0.5\"\n\t\t\t\t\t\t\tbafg-before-label=\"Before\"\n\t\t\t\t\t\t\tbafg-after-label=\"After\"\n\t\t\t\t\t\t\tbafg-overlay=\"1\"\n\t\t\t\t\t\t\tbafg-move-slider-on-hover=\"\"\n\t\t\t\t\t\t\tbafg-click-to-move=\"\"\n\t\t\t\t\t\t\tbafg-autoslide=\"false\" bafg-handle=\"\"\n\t\t\t\t\t\t\tbafg-enable-img-link=\"\"\n\t\t\t\t\t\t\tbafg-open-link=\"\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<img class=\" bafg-before-image  \"\n\t\t\t\t\t\t\t\t\tsrc=\"https:\/\/www.schaaf-gmbh.com\/wp-content\/uploads\/produkte\/hm_ssv\/pg12\/pg12_offen.jpg\" alt=\"\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<img class=\"  bafg-after-image \"\n\t\t\t\t\t\t\t\t\tsrc=\"https:\/\/www.schaaf-gmbh.com\/wp-content\/uploads\/produkte\/hm_ssv\/pg12\/pg12_geschlossen.jpg\" alt=\"\">\n\n\t\t\t\t\t\t\t\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"bafg-slider-info-wraper\">\n\t\t<div style=\"   float: right; width: 100%; \" class=\"slider-info-57749 bafg-slider-info\">\n\t\t\t\t\t<\/div>\n\t<\/div>\n\t\n\t\t\t<style>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t.slider-57749 .twentytwenty-overlay:hover {\n\t\t\t\t\t\tbackground-color:\n\t\t\t\t\t\t\trgba(0, 0, 0, 0.5)\t\t\t\t\t\t;\n\t\t\t\t\t}\n\n\t\t\t\t\t\t\t\t<\/style>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/section>\r\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ada34d5 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ada34d5\" data-element_type=\"section\" data-e-type=\"section\">\r\n\t\t\r\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-f9d396d\" data-id=\"f9d396d\" data-element_type=\"column\" data-e-type=\"column\">\r\n\t\t\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\r\n\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-fd11595 col-sm-12 col-12 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"fd11595\" data-element_type=\"section\" data-e-type=\"section\">\r\n\t\t\r\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-f95289f col-sm-3 col-4\" data-id=\"f95289f\" data-element_type=\"column\" data-e-type=\"column\">\r\n\t\t\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\r\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-74b282e elementor-widget elementor-widget-image\" data-id=\"74b282e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"579\" height=\"636\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" class=\"attachment-large size-large wp-image-2199 lazyload\" alt=\"Symbole de production hauseigene DE\" data-src=\"https:\/\/www.schaaf-gmbh.com\/wp-content\/uploads\/hauseigene_produktion_de.png\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-9c64f42 col-sm-3 col-4\" data-id=\"9c64f42\" data-element_type=\"column\" data-e-type=\"column\">\r\n\t\t\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\r\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f254963 elementor-widget elementor-widget-image\" data-id=\"f254963\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"182\" height=\"200\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" class=\"attachment-large size-large wp-image-2193 lazyload\" alt=\"Gestion de la qualit\u00e9\" data-src=\"https:\/\/www.schaaf-gmbh.com\/wp-content\/uploads\/qualitaetsmanagement_fr.png\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-75dee63 col-sm-3 col-4\" data-id=\"75dee63\" data-element_type=\"column\" data-e-type=\"column\">\r\n\t\t\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\r\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8023be0 elementor-widget elementor-widget-image\" data-id=\"8023be0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"579\" height=\"636\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" class=\"attachment-large size-large wp-image-5927 lazyload\" alt=\"Fabriqu\u00e9 en Allemagne SCHAAF GmbH &amp; Co. KG\" data-src=\"https:\/\/www.schaaf-gmbh.com\/wp-content\/uploads\/produkte\/symbole\/made_in_germany.png\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-ccba127 col-sm-3 col-4\" data-id=\"ccba127\" data-element_type=\"column\" data-e-type=\"column\">\r\n\t\t\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\r\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8ccbb58 elementor-widget elementor-widget-image\" data-id=\"8ccbb58\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"182\" height=\"200\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" class=\"attachment-large size-large wp-image-2181 lazyload\" alt=\"Solutions individuelles\" data-src=\"https:\/\/www.schaaf-gmbh.com\/wp-content\/uploads\/individuelle_loesungen_fr.png\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/section>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-5cf3043\" data-id=\"5cf3043\" data-element_type=\"column\" data-e-type=\"column\">\r\n\t\t\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\r\n\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-3dda69d col-sm-12 col-12 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3dda69d\" data-element_type=\"section\" data-e-type=\"section\">\r\n\t\t\r\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-71ea57e col-sm-3 col-4\" data-id=\"71ea57e\" data-element_type=\"column\" data-e-type=\"column\">\r\n\t\t\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\r\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-03deb59 elementor-widget elementor-widget-image\" data-id=\"03deb59\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.schaaf-gmbh.com\/wp-content\/uploads\/media_flash\/pg12_hm\/index.html\" target=\"_blank\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"182\" height=\"200\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" class=\"elementor-animation-grow attachment-large size-large wp-image-53119 lazyload\" alt=\"Montage Symbol\" data-src=\"https:\/\/www.schaaf-gmbh.com\/wp-content\/uploads\/mounting_fr.png\">\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-1148fdd col-sm-3 col-4\" data-id=\"1148fdd\" data-element_type=\"column\" data-e-type=\"column\">\r\n\t\t\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\r\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-536f66a elementor-widget elementor-widget-image\" data-id=\"536f66a\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.schaaf-gmbh.com\/wp-content\/uploads\/media_flash\/pg12_hm\/dismounting.html\" target=\"_blank\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"182\" height=\"200\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" class=\"elementor-animation-grow attachment-large size-large wp-image-53110 lazyload\" alt=\"Demontage Symbol\" data-src=\"https:\/\/www.schaaf-gmbh.com\/wp-content\/uploads\/dismounting_fr.png\">\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-7f4fae1 col-sm-3 col-4\" data-id=\"7f4fae1\" data-element_type=\"column\" data-e-type=\"column\">\r\n\t\t\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\r\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-67a3683 elementor-widget elementor-widget-image\" data-id=\"67a3683\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.schaaf-gmbh.com\/wp-content\/uploads\/media\/_Franzoesisch_Werbematerial\/Einzelbroschueren_und_Einleger\/02_Bolt_Tensioning\/SCHAAF_02,00-Bolt_Tensioning_FR.pdf\" target=\"_blank\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" title=\"\" alt=\"\" class=\"elementor-animation-grow lazyload\" loading=\"lazy\" data-src=\"https:\/\/www.schaaf-gmbh.com\/wp-content\/uploads\/2021\/06\/schaaf_icon_broschuere_blau.jpg\">\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-97ff8f1 col-sm-3 col-4\" data-id=\"97ff8f1\" data-element_type=\"column\" data-e-type=\"column\">\r\n\t\t\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\r\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-55a16fd elementor-widget elementor-widget-image\" data-id=\"55a16fd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.schaaf-gmbh.com\/wp-content\/uploads\/media\/_Englisch_Werbematerial\/Single_brochures_and_Sheets\/02_Bolt_Tensioning\/Inquiry_forms_Safety_and_Advantages\/SCHAAF_02,01-HM_Inquiry-form_GB.pdf\" target=\"_blank\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" title=\"\" alt=\"\" class=\"elementor-animation-grow lazyload\" loading=\"lazy\" data-src=\"https:\/\/www.schaaf-gmbh.com\/wp-content\/uploads\/inquiryform_gb-7.png\">\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/section>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/section>\r\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7a0311b elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7a0311b\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\r\n\t\t\r\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-db8adf8\" data-id=\"db8adf8\" data-element_type=\"column\" data-e-type=\"column\">\r\n\t\t\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\r\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2b42711 elementor-arrows-position-outside elementor-pagination-position-outside elementor-widget elementor-widget-image-carousel\" data-id=\"2b42711\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;effect&quot;:&quot;fade&quot;,&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Carrousel d\u2019images\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper swiper-image-stretch\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 sur 7\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image lazyload\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" alt=\"HM Grundstellung\" data-src=\"https:\/\/www.schaaf-gmbh.com\/wp-content\/uploads\/produkte\/hm_ssv\/schaaf_bolttensioner_hm_grundstellung.png\"><figcaption class=\"elementor-image-carousel-caption\"><h4 class=\"produktpunkte_h4\">Configuration de base<\/h4><p class=\"produktpunkte_text\">Vissez l'\u00e9crou hydraulique (HM) sur le boulon \u00e0 pr\u00e9contraindre, jusqu'\u00e0 la surface des brides. Un g\u00e9n\u00e9rateur hydraulique haute pression injecte de l'huile \u00e0 travers un tuyau haute pression dans l'espace entre le cylindre et le piston, entra\u00eenant ainsi une \u00e9l\u00e9vation de la pression hydraulique.<\/p><\/figcaption><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 sur 7\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image lazyload\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" alt=\"HM Kolben\" data-src=\"https:\/\/www.schaaf-gmbh.com\/wp-content\/uploads\/produkte\/hm_ssv\/schaaf_bolttensioner_hm_kolben.png\"><figcaption class=\"elementor-image-carousel-caption\"><h4 class=\"produktpunkte_h4\">Piston<\/h4><\/figcaption><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 sur 7\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image lazyload\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" alt=\"HM Zu spannende Schraube\" data-src=\"https:\/\/www.schaaf-gmbh.com\/wp-content\/uploads\/produkte\/hm_ssv\/schaaf_bolttensioner_hm_schraube.png\"><figcaption class=\"elementor-image-carousel-caption\"><h4 class=\"produktpunkte_h4\">Boulon \u00e0 pr\u00e9-tensionner<\/h4><\/figcaption><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 sur 7\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image lazyload\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" alt=\"HM Zylinder\" data-src=\"https:\/\/www.schaaf-gmbh.com\/wp-content\/uploads\/produkte\/hm_ssv\/schaaf_bolttensioner_hm_zylinder.png\"><figcaption class=\"elementor-image-carousel-caption\"><h4 class=\"produktpunkte_h4\">Cylindre<\/h4><\/figcaption><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"5 sur 7\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image lazyload\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" alt=\"HM Dehnung und Stauchung\" data-src=\"https:\/\/www.schaaf-gmbh.com\/wp-content\/uploads\/produkte\/hm_ssv\/schaaf_bolttensioner_hm_dehnung_stauchung.png\"><figcaption class=\"elementor-image-carousel-caption\"><h4 class=\"produktpunkte_h4\">Allongement du boulon<\/h4><p class=\"produktpunkte_text\">Gr\u00e2ce \u00e0 la pression croissante et \u00e0 la force axiale r\u00e9sultante, le boulon s'allonge et les parties de la bride sont compress\u00e9es. L'\u00e9crou de blocage se soul\u00e8ve du cylindre. Une fois la force de pr\u00e9-tension pr\u00e9r\u00e9gl\u00e9e est atteinte, l'alimentation en pression est arr\u00eat\u00e9e.<\/p><\/figcaption><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"6 sur 7\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image lazyload\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" alt=\"HM Sicherungsmutter\" data-src=\"https:\/\/www.schaaf-gmbh.com\/wp-content\/uploads\/produkte\/hm_ssv\/schaaf_bolttensioner_hm_sicherungsmutter.png\"><figcaption class=\"elementor-image-carousel-caption\"><h4 class=\"produktpunkte_h4\">\u00c9crou de blocage<\/h4><\/figcaption><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"7 sur 7\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image lazyload\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" alt=\"HM Beidrehen der Sicherungsmutter\" data-src=\"https:\/\/www.schaaf-gmbh.com\/wp-content\/uploads\/produkte\/hm_ssv\/schaaf_bolttensioner_hm_beidrehen.png\"><figcaption class=\"elementor-image-carousel-caption\"><h4 class=\"produktpunkte_h4\">Vissage de l'\u00e9crou de blocage<\/h4><p class=\"produktpunkte_text\">La force de pr\u00e9contrainte a \u00e9t\u00e9 atteinte, et l'\u00e9crou de blocage est tourn\u00e9 manuellement jusqu'\u00e0 la but\u00e9e du cylindre. Ainsi, la force de pr\u00e9contrainte est maintenue dans l'assemblage, et le syst\u00e8me hydraulique peut \u00eatre d\u00e9connect\u00e9. L'\u00e9crou hydraulique reste fix\u00e9 \u00e0 la connexion du boulon.<\/p><\/figcaption><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/section>\r\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3ce9422 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3ce9422\" data-element_type=\"section\" data-e-type=\"section\">\r\n\t\t\r\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5daf174\" data-id=\"5daf174\" data-element_type=\"column\" data-e-type=\"column\">\r\n\t\t\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\r\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6cddcc1 elementor-widget elementor-widget-heading\" data-id=\"6cddcc1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Avantages<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-830636e elementor-widget elementor-widget-accordion\" data-id=\"830636e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-accordion\">\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1371\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-1371\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Capacit\u00e9 de Tensionnement Simultan\u00e9 \u00e0 Plusieurs Points<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1371\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-1371\"><p style=\"padding-left: 40px;\">Le \u00ab\u00a0serrage crois\u00e9\u00a0\u00bb de plusieurs boulons \u00e0 plusieurs points n&rsquo;est plus n\u00e9cessaire, car les syst\u00e8mes SSV et HM de SCHAAF permettent de serrer toutes les connexions boulonn\u00e9es simultan\u00e9ment avec la m\u00eame force de tension. Cela s&rsquo;applique \u00e9galement lors de l&rsquo;augmentation de la force de tension.<\/p>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1372\" class=\"elementor-tab-title\" data-tab=\"2\" role=\"button\" aria-controls=\"elementor-tab-content-1372\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">D\u00e9but de la Tension Ind\u00e9pendamment du Trajet de Tensionnement<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1372\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"region\" aria-labelledby=\"elementor-tab-title-1372\"><p style=\"padding-left: 40px;\">Contrairement aux proc\u00e9dures de d\u00e9marrage des vis thermiques, les syst\u00e8mes SCHAAF SSV et HM permettent d&rsquo;\u00e9liminer les \u00e9carts entre les composants individuels. Chaque boulon peut \u00eatre tendu avec exactement la m\u00eame force, et ce, sans parcourir la m\u00eame distance!<\/p>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1373\" class=\"elementor-tab-title\" data-tab=\"3\" role=\"button\" aria-controls=\"elementor-tab-content-1373\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Capacit\u00e9 de test rapide \u00e0 tout moment<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1373\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"region\" aria-labelledby=\"elementor-tab-title-1373\"><p style=\"padding-left: 40px;\">Les syst\u00e8mes SCHAAF SSV et HM permettent d&rsquo;appliquer une force de tension r\u00e9siduelle gr\u00e2ce \u00e0 l&rsquo;application d&rsquo;une force de test, afin de d\u00e9terminer si un affaissement de la vis peut se produire et, le cas \u00e9ch\u00e9ant, de l&rsquo;\u00e9liminer.<\/p>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1374\" class=\"elementor-tab-title\" data-tab=\"4\" role=\"button\" aria-controls=\"elementor-tab-content-1374\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Application universelle<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1374\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"4\" role=\"region\" aria-labelledby=\"elementor-tab-title-1374\"><p style=\"padding-left: 40px;\">Avec une unit\u00e9 compacte et la possibilit\u00e9 d&rsquo;interchanger les pi\u00e8ces en fonction de la taille du boulon, les SSV de SCHAAFpeut \u00e9galement \u00eatre utilis\u00e9 pour d&rsquo;autres tailles de filetage.<\/p>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1375\" class=\"elementor-tab-title\" data-tab=\"5\" role=\"button\" aria-controls=\"elementor-tab-content-1375\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Gain de temps<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1375\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"5\" role=\"region\" aria-labelledby=\"elementor-tab-title-1375\"><p style=\"padding-left: 40px;\">Les syst\u00e8mes SSV et HM permettent de r\u00e9duire consid\u00e9rablement le temps n\u00e9cessaire pour les applications de tension. Cet effet s&rsquo;intensifie pour des forces de tension plus \u00e9lev\u00e9es, des diam\u00e8tres de filets de boulons plus grands et \u00e9galement lors de l&rsquo;installation de plusieurs SSV ou HM. Des \u00e9conomies de temps allant jusqu&rsquo;\u00e0 99 % sont possibles ! Il n&rsquo;est plus n\u00e9cessaire d&rsquo;appliquer un grand couple \u00e0 la main. De nombreuses fonctionnalit\u00e9s de manipulation sont disponibles, con\u00e7ues pour faciliter le travail avec les tendeurs de boulons SCHAAF et les \u00e9crous hydrauliques, notamment pour les grandes dimensions.<\/p>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-90f3e7e elementor-widget elementor-widget-heading\" data-id=\"90f3e7e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Caract\u00e9ristiques des HM PG12<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e3d32ea elementor-widget elementor-widget-text-editor\" data-id=\"e3d32ea\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul class=\"liste\">\n<li>Dimensions g\u00e9om\u00e9triques plus petites par rapport au PG 11<\/li>\n<li>Court d\u00e9passement de filetage<\/li>\n<li>Force de pr\u00e9-tension \u00e9lev\u00e9e avec le plus petit diam\u00e8tre ext\u00e9rieur<\/li>\n<li>Guidage du piston stable<\/li>\n<li>Force de pr\u00e9-tension maintenue sans pression<\/li>\n<\/ul>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-32dd28f elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"32dd28f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/section>\r\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2d8b70a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2d8b70a\" data-element_type=\"section\" data-e-type=\"section\">\r\n\t\t\r\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b3d0102\" data-id=\"b3d0102\" data-element_type=\"column\" data-e-type=\"column\">\r\n\t\t\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\r\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bd8fa04 elementor-widget elementor-widget-heading\" data-id=\"bd8fa04\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Plus d'\u00e9crous hydrauliques<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/section>\r\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-bd7fdd4 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"bd7fdd4\" data-element_type=\"section\" data-e-type=\"section\">\r\n\t\t\r\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7f7ee16\" data-id=\"7f7ee16\" data-element_type=\"column\" data-e-type=\"column\">\r\n\t\t\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\r\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0d7e8b9 elementor-widget elementor-widget-shortcode\" data-id=\"0d7e8b9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\">\t\t<div data-elementor-type=\"section\" data-elementor-id=\"44413\" class=\"elementor elementor-44413 elementor-44396 elementor-44396\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-37347470 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"37347470\" data-element_type=\"section\" data-e-type=\"section\">\r\n\t\t\r\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-9cd517a col-sm-12 col-lg-4 elementor-invisible\" data-id=\"9cd517a\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeIn&quot;}\">\r\n\t\t\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\r\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d59886a elementor-widget elementor-widget-image\" data-id=\"d59886a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.schaaf-gmbh.com\/fr\/elements-dassemblage\/hydraulikmutter\/hm-pg9\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"352\" height=\"336\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" class=\"elementor-animation-float attachment-large size-large wp-image-8732 lazyload\" alt=\"Icon PG9\" data-src=\"https:\/\/www.schaaf-gmbh.com\/wp-content\/uploads\/produkte\/hm_ssv\/pg9\/schaaf_bolttensioner_pg9-1.png\">\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-25919f9a produktbezeichnung elementor-widget elementor-widget-text-editor\" data-id=\"25919f9a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: left;\">Un HM du <strong>groupe de produits 9<\/strong> se caract\u00e9rise par le fait qu&rsquo;une force axiale est g\u00e9n\u00e9r\u00e9e et peut \u00eatre maintenue par pressurisation<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-176c2c4 col-sm-12 col-lg-4 elementor-invisible\" data-id=\"176c2c4\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeIn&quot;}\">\r\n\t\t\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\r\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2793b5e4 elementor-widget elementor-widget-image\" data-id=\"2793b5e4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.schaaf-gmbh.com\/fr\/elements-dassemblage\/hydraulikmutter\/hm-pg10\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"352\" height=\"336\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" class=\"elementor-animation-float attachment-large size-large wp-image-25027 lazyload\" alt=\"HM PG10 Produkt\u00fcbersicht\" data-src=\"https:\/\/www.schaaf-gmbh.com\/wp-content\/uploads\/produkte\/hm_ssv\/pg10\/schaaf_bolttensioner_pg10_produktuebersicht.png\">\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-754e05e7 produktbezeichnung elementor-widget elementor-widget-text-editor\" data-id=\"754e05e7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: left;\">Un HM du <strong>groupe de produits 10<\/strong> se caract\u00e9rise par le fait que la force de pr\u00e9-tension transmise par un piston annulaire est maintenue par un contre-\u00e9l\u00e9ment m\u00e9canique, sans que l&rsquo;\u00e9crou hydraulique ne soit laiss\u00e9 sous pression en permanence<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-66865234 col-sm-12 col-lg-4 elementor-invisible\" data-id=\"66865234\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeIn&quot;}\">\r\n\t\t\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\r\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6cf34116 elementor-widget elementor-widget-image\" data-id=\"6cf34116\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.schaaf-gmbh.com\/fr\/elements-dassemblage\/hydraulikmutter\/hm-pg11\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"352\" height=\"336\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" class=\"elementor-animation-float attachment-large size-large wp-image-8746 lazyload\" alt=\"Icon PG11\" data-src=\"https:\/\/www.schaaf-gmbh.com\/wp-content\/uploads\/produkte\/hm_ssv\/pg11\/schaaf_bolttensioner_pg11.png\">\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-403a2863 produktbezeichnung elementor-widget elementor-widget-text-editor\" data-id=\"403a2863\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Un HM du <strong>groupe de produits 11<\/strong> se caract\u00e9rise par le fait que la force de pr\u00e9-tension transmise par un piston \u00e0 \u00e9tages est maintenue par un \u00e9l\u00e9ment de vis distinct du cylindre de pression, sans que l&rsquo;\u00e9crou hydraulique ne soit laiss\u00e9 sous pression en permanence<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/section>\r\n\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/section>\r\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2bae20e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2bae20e\" data-element_type=\"section\" data-e-type=\"section\">\r\n\t\t\r\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d4e4355\" data-id=\"d4e4355\" data-element_type=\"column\" data-e-type=\"column\">\r\n\t\t\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\r\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-01a149f elementor-widget elementor-widget-shortcode\" data-id=\"01a149f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\">\t\t<div data-elementor-type=\"section\" data-elementor-id=\"44415\" class=\"elementor elementor-44415 elementor-44399 elementor-44399\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2b91d8c8 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2b91d8c8\" data-element_type=\"section\" data-e-type=\"section\">\r\n\t\t\r\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-6e0b4780 col-sm-12 col-lg-4 elementor-invisible\" data-id=\"6e0b4780\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeIn&quot;}\">\r\n\t\t\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\r\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4fe568ff elementor-widget elementor-widget-image\" data-id=\"4fe568ff\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.schaaf-gmbh.com\/fr\/elements-dassemblage\/hydraulikmutter\/hm-pg12\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"352\" height=\"336\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" class=\"elementor-animation-float attachment-large size-large wp-image-25041 lazyload\" alt=\"HM PG12 Produkt\u00fcbersicht\" data-src=\"https:\/\/www.schaaf-gmbh.com\/wp-content\/uploads\/produkte\/hm_ssv\/pg12\/schaaf_bolttensioner_pg12_produktuebersicht.png\">\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-32dfc45e produktbezeichnung elementor-widget elementor-widget-text-editor\" data-id=\"32dfc45e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: left;\">Un HM du <strong>groupe de produits 12<\/strong> se caract\u00e9rise par le fait que la force de pr\u00e9-tension transmise par un piston \u00e0 \u00e9tages est maintenue par un contre-\u00e9l\u00e9ment m\u00e9canique, sans que l&rsquo;\u00e9crou hydraulique ne soit laiss\u00e9 sous pression en permanence<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-251a1e53 col-sm-12 col-lg-4 elementor-invisible\" data-id=\"251a1e53\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeIn&quot;}\">\r\n\t\t\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\r\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-58edb90e elementor-widget elementor-widget-image\" data-id=\"58edb90e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.schaaf-gmbh.com\/fr\/elements-dassemblage\/hydraulikmutter\/hm-pg13\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"352\" height=\"336\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" class=\"elementor-animation-float attachment-large size-large wp-image-8760 lazyload\" alt=\"HM PG12 Produkt\u00fcbersicht\" data-src=\"https:\/\/www.schaaf-gmbh.com\/wp-content\/uploads\/produkte\/hm_ssv\/pg13\/schaaf_bolttensioner_pg13_produktuebersicht.png\">\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-65a9b35c produktbezeichnung elementor-widget elementor-widget-text-editor\" data-id=\"65a9b35c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Un HM du <strong>groupe de produits 13<\/strong> se caract\u00e9rise par le fait que plusieurs \u00e9crous hydrauliques sont int\u00e9gr\u00e9s en tant que compos\u00e9 dans ou sur un anneau ou une structure similaire, permettant ainsi de pr\u00e9-tendre plusieurs filets de boulons simultan\u00e9ment<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-5eb31871\" data-id=\"5eb31871\" data-element_type=\"column\" data-e-type=\"column\">\r\n\t\t\t\t\t<div class=\"elementor-widget-wrap\">\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/section>\r\n\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/section>\r\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b558da6 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b558da6\" data-element_type=\"section\" data-e-type=\"section\">\r\n\t\t\r\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-9183aff\" data-id=\"9183aff\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\r\n\t\t\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\r\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1314bfb elementor-widget elementor-widget-image\" data-id=\"1314bfb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" title=\"hm-solutions sp\u00e9ciales\" alt=\"HM Speziall\u00f6sungen\" loading=\"lazy\" class=\"lazyload\" data-src=\"https:\/\/www.schaaf-gmbh.com\/wp-content\/uploads\/produkte\/hm_ssv\/schaaf_bolttensioner_hm-spezialloesungen.jpg\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7ebb64f elementor-widget elementor-widget-heading\" data-id=\"7ebb64f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Versions<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8c725cc elementor-widget elementor-widget-text-editor\" data-id=\"8c725cc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>En plus d&rsquo;un certain nombre de tendeurs de boulons et <strong>d&rsquo;\u00e9crous hydrauliques<\/strong> standardis\u00e9s, SCHAAF a d\u00e9j\u00e0 livr\u00e9 des milliers de tendeurs de boulons axiaux personnalis\u00e9s. Le syst\u00e8me CAD Design on Demand permet de r\u00e9aliser rapidement des solutions sur mesure pour les clients. Bas\u00e9es sur des techniques de pr\u00e9-tension axiale, de nombreuses solutions sp\u00e9cialis\u00e9es et brevet\u00e9es ont \u00e9t\u00e9 d\u00e9velopp\u00e9es au cours des derni\u00e8res ann\u00e9es. Les tendeurs de boulons, les \u00e9crous hydrauliques et ExpaTen, ainsi que les A-Loc et EcoRolls, d\u00e9velopp\u00e9s sp\u00e9cialement pour les laminoirs, repr\u00e9sentent tous une solution syst\u00e8me \u00e0 100 % avec les accessoires de SCHAAF, tels que les tuyaux haute pression et les g\u00e9n\u00e9rateurs haute pression.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-1993098\" data-id=\"1993098\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\r\n\t\t\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\r\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9f8c26e einsatzgebiete elementor-widget-tablet__width-inherit elementor-widget-mobile__width-inherit elementor-arrows-position-inside elementor-widget elementor-widget-image-carousel\" data-id=\"9f8c26e\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;arrows&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Carrousel d\u2019images\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper swiper-image-stretch\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 sur 3\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image lazyload\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" alt=\"Allgemeiner Maschinenbau Einsatzgebiete SMS group\" data-src=\"https:\/\/www.schaaf-gmbh.com\/wp-content\/uploads\/branchenloesung\/einsatzgebiete_am.jpg\"><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 sur 3\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image lazyload\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" alt=\"Hochau und Tiefbau Einsatzgebiete\" data-src=\"https:\/\/www.schaaf-gmbh.com\/wp-content\/uploads\/branchenloesung\/einsatzgebiete_hochbau_tiefbau.jpg\"><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 sur 3\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image lazyload\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" alt=\"Chemische Industrie Einsatzgebiete\" data-src=\"https:\/\/www.schaaf-gmbh.com\/wp-content\/uploads\/branchenloesung\/einsatzgebiete_chemische_industrie.jpg\"><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1e4ee7f elementor-widget elementor-widget-heading\" data-id=\"1e4ee7f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Domaines d'application<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-746ec3b elementor-widget elementor-widget-text-editor\" data-id=\"746ec3b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Les domaines d&rsquo;application des tendeurs de boulons et des <strong>\u00e9crous hydrauliques<\/strong> sont illimit\u00e9s. La diversit\u00e9 des solutions propos\u00e9es par les utilisateurs a engendr\u00e9 un grand nombre de conceptions vari\u00e9es. C&rsquo;est pourquoi il n&rsquo;est pas toujours possible de classer tous les tendeurs de boulons et \u00e9crous hydrauliques dans un groupe de produits sp\u00e9cifique.<\/p>\n<p>Par exemple, la force de tension peut \u00eatre transmise par un filetage ou un syst\u00e8me \u00e0 ba\u00efonnette. N&rsquo;h\u00e9sitez pas \u00e0 nous contacter pour discuter de votre application particuli\u00e8re.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/section>\r\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ec69e05 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ec69e05\" data-element_type=\"section\" data-e-type=\"section\">\r\n\t\t\r\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-e2b3a3e\" data-id=\"e2b3a3e\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\r\n\t\t\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\r\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1325422 elementor-widget elementor-widget-image\" data-id=\"1325422\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" title=\"qualitaetsmanagement_small\" alt=\"Qualit\u00e9\" loading=\"lazy\" class=\"lazyload\" data-src=\"https:\/\/www.schaaf-gmbh.com\/wp-content\/uploads\/qualitaetsmanagement_small.jpg\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-621e85e elementor-widget elementor-widget-heading\" data-id=\"621e85e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Assurance qualit\u00e9<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fe0c0a2 elementor-widget elementor-widget-text-editor\" data-id=\"fe0c0a2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Les outils de tensionnement de boulons et <strong>\u00e9crous hydrauliques<\/strong> sont soumis \u00e0 des contr\u00f4les rigoureux pour garantir leur fiabilit\u00e9. Cela inclut la v\u00e9rification de la qualit\u00e9 des mat\u00e9riaux, la pr\u00e9cision dimensionnelle, le bon fonctionnement et la r\u00e9sistance \u00e0 la pression. Gr\u00e2ce \u00e0 des mesures d&rsquo;assurance qualit\u00e9 tout au long du processus de fabrication, chaque produit est soigneusement inspect\u00e9.<\/p>\n<p>De plus, la documentation d\u00e9taill\u00e9e fournie avec chaque outil assure une utilisation correcte et s\u00e9curis\u00e9e.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-26f6f7b elementor-align-justify elementor-widget elementor-widget-button\" data-id=\"26f6f7b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.schaaf-gmbh.com\/fr\/unternehmen\/zertifizierungen\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"  Simple-Line-Icons-arrow-right\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Plus d'informations sur les certifications du SCHAAF<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-ffeb7c7\" data-id=\"ffeb7c7\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\r\n\t\t\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\r\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a68de28 elementor-widget elementor-widget-image\" data-id=\"a68de28\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" title=\"serviceleistung_small\" alt=\"Performances des services\" loading=\"lazy\" class=\"lazyload\" data-src=\"https:\/\/www.schaaf-gmbh.com\/wp-content\/uploads\/sortieren\/serviceleistung_small.jpg\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-af1f5fa elementor-widget elementor-widget-heading\" data-id=\"af1f5fa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Services<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-86cb155 elementor-widget elementor-widget-text-editor\" data-id=\"86cb155\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Les SSV et <strong>HM<\/strong> sont, bien s\u00fbr, livr\u00e9s emball\u00e9s, pr\u00eats \u00e0 \u00eatre install\u00e9s et mis en service.<\/p>\n<p>Les SSV et <strong>HM<\/strong> SCHAAF sont conviviaux, fiables et fabriqu\u00e9s selon les normes les plus \u00e9lev\u00e9es en mati\u00e8re de savoir-faire technique. Notre personnel hautement motiv\u00e9 sera ravi de former votre personnel, sur site ou dans nos ateliers, \u00e0 la manipulation g\u00e9n\u00e9rale des \u00e9quipements haute pression.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2cd900b elementor-align-justify elementor-widget elementor-widget-button\" data-id=\"2cd900b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.schaaf-gmbh.com\/fr\/service\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"  Simple-Line-Icons-arrow-right\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Plus d'informations sur SCHAAF Service GmbH<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/section>\r\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-86b1f7c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"86b1f7c\" data-element_type=\"section\" data-e-type=\"section\">\r\n\t\t\r\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0b4b75a\" data-id=\"0b4b75a\" data-element_type=\"column\" data-e-type=\"column\">\r\n\t\t\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\r\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-849d47a elementor-widget elementor-widget-spacer\" data-id=\"849d47a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/section>\r\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9835f90 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9835f90\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\r\n\t\t\r\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-90d186e\" data-id=\"90d186e\" data-element_type=\"column\" data-e-type=\"column\">\r\n\t\t\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\r\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2aedfec elementor-widget elementor-widget-heading\" data-id=\"2aedfec\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">ACCESSOIRES ASSOCI\u00c9S<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-585746f elementor-widget elementor-widget-shortcode\" data-id=\"585746f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\">\t\t<div data-elementor-type=\"section\" data-elementor-id=\"43296\" class=\"elementor elementor-43296 elementor-43257 elementor-43257\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-50ab7d89 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"50ab7d89\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\r\n\t\t\r\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-1c0945ff\" data-id=\"1c0945ff\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\r\n\t\t\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\r\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4da937aa elementor-widget elementor-widget-image\" data-id=\"4da937aa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.schaaf-gmbh.com\/fr\/produkterweiterungen\/handhebelpumpen\/\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" title=\"\" alt=\"\" loading=\"lazy\" class=\"lazyload\" data-src=\"https:\/\/www.schaaf-gmbh.com\/wp-content\/uploads\/produkte\/pg22\/pg22_hp1600.png\">\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-114957c0 elementor-widget elementor-widget-heading\" data-id=\"114957c0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/www.schaaf-gmbh.com\/fr\/produkterweiterungen\/handhebelpumpen\/\"> Pompes \u00e0 levier manuel<\/a><\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-235b4f97 elementor-widget elementor-widget-text-editor\" data-id=\"235b4f97\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La pompe \u00e0 levier manuel est enti\u00e8rement assembl\u00e9e et pr\u00eate \u00e0 l&#8217;emploi, capable de g\u00e9n\u00e9rer des pressions allant jusqu&rsquo;\u00e0 4 000 bars<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-464b5398 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"464b5398\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<a class=\"elementor-icon\" href=\"https:\/\/www.schaaf-gmbh.com\/fr\/produkterweiterungen\/handhebelpumpen\/\">\n\t\t\t<i aria-hidden=\"true\" class=\"  Simple-Line-Icons-arrow-right\"><\/i>\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-5501a6de\" data-id=\"5501a6de\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\r\n\t\t\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\r\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1e7e3fc0 elementor-widget elementor-widget-image\" data-id=\"1e7e3fc0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.schaaf-gmbh.com\/fr\/produkterweiterungen\/pumpenaggregate\/\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" title=\"\" alt=\"\" loading=\"lazy\" class=\"lazyload\" data-src=\"https:\/\/www.schaaf-gmbh.com\/wp-content\/uploads\/produkte\/pg22\/pg28_mds.png\">\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6f3a57d0 elementor-widget elementor-widget-heading\" data-id=\"6f3a57d0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/www.schaaf-gmbh.com\/fr\/produkterweiterungen\/pumpenaggregate\/\">Unit\u00e9s \u00e0 haute pression<\/a><\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4b8cb17f elementor-widget elementor-widget-text-editor\" data-id=\"4b8cb17f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>G\u00e9n\u00e9rateurs haute pression parfaitement adapt\u00e9s \u00e0 nos outils haute pression<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-33163e71 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"33163e71\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<a class=\"elementor-icon\" href=\"https:\/\/www.schaaf-gmbh.com\/fr\/produkterweiterungen\/pumpenaggregate\/\">\n\t\t\t<i aria-hidden=\"true\" class=\"  Simple-Line-Icons-arrow-right\"><\/i>\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-4c529f48\" data-id=\"4c529f48\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\r\n\t\t\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\r\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-612a77a9 elementor-widget elementor-widget-image\" data-id=\"612a77a9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.schaaf-gmbh.com\/fr\/produkterweiterungen\/zubehoer\/\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" title=\"\" alt=\"\" loading=\"lazy\" class=\"lazyload\" data-src=\"https:\/\/www.schaaf-gmbh.com\/wp-content\/uploads\/produkte\/zubehoer\/pg20_nippel_adapter.png\">\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-11b53255 elementor-widget elementor-widget-heading\" data-id=\"11b53255\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/www.schaaf-gmbh.com\/fr\/produkterweiterungen\/zubehoer\/\">Accessoires<\/a><\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-742f01af elementor-widget elementor-widget-text-editor\" data-id=\"742f01af\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Accessoires hydrauliques haute pression sp\u00e9cialement adapt\u00e9s \u00e0 la fonction<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-32026ff0 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"32026ff0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<a class=\"elementor-icon\" href=\"https:\/\/www.schaaf-gmbh.com\/fr\/produkterweiterungen\/zubehoer\/\">\n\t\t\t<i aria-hidden=\"true\" class=\"  Simple-Line-Icons-arrow-right\"><\/i>\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/section>\r\n\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/section>\r\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d6ab22c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d6ab22c\" data-element_type=\"section\" data-e-type=\"section\">\r\n\t\t\r\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0b012f4\" data-id=\"0b012f4\" data-element_type=\"column\" data-e-type=\"column\">\r\n\t\t\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\r\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-28173d6 elementor-widget elementor-widget-heading\" data-id=\"28173d6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">M\u00c9DIAS ET PLUS<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7d0e447 elementor-widget elementor-widget-shortcode\" data-id=\"7d0e447\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\">\t\t<div data-elementor-type=\"section\" data-elementor-id=\"43320\" class=\"elementor elementor-43320 elementor-36271 elementor-36271\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1adba38 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1adba38\" data-element_type=\"section\" data-e-type=\"section\">\r\n\t\t\r\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-49183953\" data-id=\"49183953\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\r\n\t\t\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\r\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-40298ec9 elementor-widget elementor-widget-image\" data-id=\"40298ec9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.schaaf-gmbh.com\/fr\/download\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"338\" height=\"233\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" class=\"elementor-animation-float attachment-large size-large wp-image-16837 lazyload\" alt=\"Bolt Tensioning DE Brosch\u00fcre\" data-src=\"https:\/\/www.schaaf-gmbh.com\/wp-content\/uploads\/download\/schaaf_0200-bolt_tensioning_de.jpg\">\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6b6c960f elementor-widget elementor-widget-heading\" data-id=\"6b6c960f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Impression \/ Animation<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-27fd0193 elementor-widget elementor-widget-text-editor\" data-id=\"27fd0193\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Lire toutes les informations.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4ce8576c elementor-align-justify elementor-widget__width-inherit button_medien elementor-absolute elementor-widget elementor-widget-button\" data-id=\"4ce8576c\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-xs\" href=\"https:\/\/www.schaaf-gmbh.com\/fr\/download\/\" id=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"  Simple-Line-Icons-arrow-right\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">TOUS LES T\u00c9L\u00c9CHARGEMENTS<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-7d28a6c2\" data-id=\"7d28a6c2\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\r\n\t\t\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\r\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6640b550 elementor-widget elementor-widget-image\" data-id=\"6640b550\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.schaaf-gmbh.com\/fr\/elements-de-connexion\/schraubenspannvorrichtung\/ssv-pg1\/referenzen-2\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"707\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" class=\"elementor-animation-float attachment-large size-large wp-image-1215 lazyload\" alt=\"Schaaf Montagebild\" sizes=\"(max-width: 1024px) 100vw, 1024px\" data-src=\"https:\/\/www.schaaf-gmbh.com\/wp-content\/uploads\/aktuelles\/schaaf_aktuelles-1024x707.jpg\" data-srcset=\"https:\/\/www.schaaf-gmbh.com\/wp-content\/uploads\/aktuelles\/schaaf_aktuelles-1024x707.jpg 1024w, https:\/\/www.schaaf-gmbh.com\/wp-content\/uploads\/aktuelles\/schaaf_aktuelles-768x530.jpg 768w, https:\/\/www.schaaf-gmbh.com\/wp-content\/uploads\/aktuelles\/schaaf_aktuelles-640x442.jpg 640w, https:\/\/www.schaaf-gmbh.com\/wp-content\/uploads\/aktuelles\/schaaf_aktuelles-400x276.jpg 400w, https:\/\/www.schaaf-gmbh.com\/wp-content\/uploads\/aktuelles\/schaaf_aktuelles-367x253.jpg 367w\">\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-186f14bf elementor-widget elementor-widget-heading\" data-id=\"186f14bf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">R\u00e9f\u00e9rences<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-46e4c4a9 elementor-widget elementor-widget-text-editor\" data-id=\"46e4c4a9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Consultez les projets compl\u00e9t\u00e9s et approuv\u00e9s concernant les SSV.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7c23b5cd elementor-align-justify elementor-widget__width-inherit elementor-absolute elementor-widget elementor-widget-button\" data-id=\"7c23b5cd\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-xs\" href=\"https:\/\/www.schaaf-gmbh.com\/fr\/elements-de-connexion\/schraubenspannvorrichtung\/ssv-pg1\/referenzen-2\/\" id=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"  Simple-Line-Icons-arrow-right\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">TOUS LES R\u00c9F\u00c9RENCES<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-1e203625\" data-id=\"1e203625\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\r\n\t\t\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\r\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6999bf80 elementor-widget elementor-widget-image\" data-id=\"6999bf80\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.schaaf-gmbh.com\/fr\/online-meeting-webinar\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"819\" height=\"583\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" class=\"elementor-animation-float attachment-large size-large wp-image-1115 lazyload\" alt=\"Webinar\" sizes=\"(max-width: 819px) 100vw, 819px\" data-src=\"https:\/\/www.schaaf-gmbh.com\/wp-content\/uploads\/online_seminar_webinar.jpg\" data-srcset=\"https:\/\/www.schaaf-gmbh.com\/wp-content\/uploads\/\/online_seminar_webinar.jpg 819w, https:\/\/www.schaaf-gmbh.com\/wp-content\/uploads\/\/online_seminar_webinar-768x547.jpg 768w, https:\/\/www.schaaf-gmbh.com\/wp-content\/uploads\/\/online_seminar_webinar-640x456.jpg 640w, https:\/\/www.schaaf-gmbh.com\/wp-content\/uploads\/\/online_seminar_webinar-400x285.jpg 400w, https:\/\/www.schaaf-gmbh.com\/wp-content\/uploads\/\/online_seminar_webinar-367x261.jpg 367w\">\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-64f07396 elementor-widget elementor-widget-heading\" data-id=\"64f07396\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">R\u00e9union en ligne \/ Webinaire   <\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4c91e0a1 elementor-widget elementor-widget-text-editor\" data-id=\"4c91e0a1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>N\u2019h\u00e9sitez pas \u00e0 nous contacter pour recevoir une pr\u00e9sentation en ligne gratuite sur ce produit.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-78a30a82 elementor-align-justify elementor-widget__width-inherit elementor-absolute elementor-widget elementor-widget-button\" data-id=\"78a30a82\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-xs\" href=\"https:\/\/www.schaaf-gmbh.com\/fr\/online-meeting-webinar\/\" id=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"  Simple-Line-Icons-arrow-right\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">INSCRIPTION<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/section>\r\n\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/section>\r\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-91fe171 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"91fe171\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\r\n\t\t\r\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8b9909e\" data-id=\"8b9909e\" data-element_type=\"column\" data-e-type=\"column\">\r\n\t\t\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\r\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7ec296c elementor-widget elementor-widget-spacer\" data-id=\"7ec296c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f64c720 elementor-widget elementor-widget-html\" data-id=\"f64c720\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t \r\n \r\n <h2>Solutions sp\u00e9cifiques \u00e0 l'industrie:<\/h2>\r\n <h4>Tous les produits SCHAAF offrent une solution individuelle pour chaque industrie.<\/h4>\r\n<h4>HM s'av\u00e8re particuli\u00e8rement efficace pour:<\/h4>\r\n\r\n<form id=\"branche\">\r\n  \r\n <input type=\"button\" class=\"industry-list__item branchenauswahl\" name =\"Button1\" id=\"AM\" onclick=\"window.location.href='\/fr\/apercu-de-solution-par-branche-dactivite\/construction-generale-de-machines\/'\" value =\"La m\u00e9canique g\u00e9n\u00e9rale\">\r\n \r\n <input type=\"button\" class=\"industry-list__item branchenauswahl_inaktiv\" name =\"Button1\" id=\"WE\" onclick=\"window.location.href='\/fr\/apercu-de-solution-par-branche-dactivite\/windenergie\/'\" value =\"Energie\u00a0\u00e9olienne\">\r\n\r\n <input type=\"button\" class=\"industry-list__item branchenauswahl_inaktiv\" name =\"Button1\" id=\"HE\" onclick=\"window.location.href='\/fr\/apercu-de-solution-par-branche-dactivite\/energie-hydrolique\/'\" value =\"Hydro\u00e9nergie\">\r\n\r\n <input type=\"button\" class=\"industry-list__item branchenauswahl_inaktiv\" name =\"Button1\" id=\"KT\" onclick=\"window.location.href='\/fr\/apercu-de-solution-par-branche-dactivite\/centrales-electriques\/'\" value =\"Centrales \u00e9lectriques\">\r\n\r\n <input type=\"button\" class=\"industry-list__item branchenauswahl_inaktiv\" name =\"Button1\" id=\"MG\" onclick=\"window.location.href='\/fr\/apercu-de-solution-par-branche-dactivite\/moteurs-et-transmissions\/'\" value =\"Moteurs et transmissions\">\r\n\r\n <input type=\"button\" class=\"industry-list__item branchenauswahl_inaktiv\" name =\"Button1\" id=\"ST\" onclick=\"window.location.href='\/fr\/apercu-de-solution-par-branche-dactivite\/technologie-de-navire\/'\" value =\"La technologie de navale\">\r\n\r\n <input type=\"button\" class=\"industry-list__item branchenauswahl_inaktiv\" name =\"Button1\" id=\"KB\" onclick=\"window.location.href='\/fr\/apercu-de-solution-par-branche-dactivite\/grues-et-engins-de-chantier\/'\" value =\"Grues et machines de construction\">\r\n\r\n <input type=\"button\" class=\"industry-list__item branchenauswahl\" name =\"Button1\" id=\"HT\" onclick=\"window.location.href='\/fr\/apercu-de-solution-par-branche-dactivite\/genie-civil\/'\" value =\"Batiments et travaux publics\">\r\n\r\n <input type=\"button\" class=\"industry-list__item branchenauswahl_inaktiv\" name =\"Button1\" id=\"MI\" onclick=\"window.location.href='\/fr\/apercu-de-solution-par-branche-dactivite\/industrie-du-metal\/'\" value =\"Industrie\u00a0m\u00e9tallurgique\">\r\n\r\n <input type=\"button\" class=\"industry-list__item branchenauswahl\" name =\"Button1\" id=\"CI\" onclick=\"window.location.href='\/fr\/apercu-de-solution-par-branche-dactivite\/industrie-chimique\/'\" value =\"Industrie chimique\">\r\n\r\n<\/form>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1d41112 elementor-widget elementor-widget-spacer\" data-id=\"1d41112\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/section>\r\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-790679d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"790679d\" data-element_type=\"section\" data-e-type=\"section\">\r\n\t\t\r\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9d6f805\" data-id=\"9d6f805\" data-element_type=\"column\" data-e-type=\"column\">\r\n\t\t\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\r\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-853aa8c elementor-widget elementor-widget-spacer\" data-id=\"853aa8c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/section>\r\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0879fb3 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0879fb3\" data-element_type=\"section\" data-e-type=\"section\">\r\n\t\t\r\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4b0ae5f\" data-id=\"4b0ae5f\" data-element_type=\"column\" data-e-type=\"column\">\r\n\t\t\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\r\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e123354 elementor-widget elementor-widget-template\" data-id=\"e123354\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"template.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-template\">\n\t\t\t\t\t<div data-elementor-type=\"section\" data-elementor-id=\"24468\" class=\"elementor elementor-24468 elementor-16790 elementor-16790\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-736ae37a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"736ae37a\" data-element_type=\"section\" data-e-type=\"section\">\r\n\t\t\r\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-4afd4609 elementor-invisible\" data-id=\"4afd4609\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeIn&quot;}\">\r\n\t\t\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\r\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-458b15e7 elementor-widget elementor-widget-image\" data-id=\"458b15e7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.schaaf-gmbh.com\/fr\/unternehmen\/news\/\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" title=\"aktuelles_schreinerei\" alt=\"Collage Schreinerei\" class=\"elementor-animation-float lazyload\" loading=\"lazy\" data-src=\"https:\/\/www.schaaf-gmbh.com\/wp-content\/uploads\/aktuelles\/aktuelles_schreinerei.jpg\">\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-75237d02 elementor-widget elementor-widget-heading\" data-id=\"75237d02\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/www.schaaf-gmbh.com\/fr\/unternehmen\/news\/\">Actualit\u00e9s<\/a><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-47c7088d elementor-invisible\" data-id=\"47c7088d\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeIn&quot;}\">\r\n\t\t\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\r\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1da9bba3 elementor-widget elementor-widget-image\" data-id=\"1da9bba3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.schaaf-gmbh.com\/fr\/contacts\/apercu-les-personnes-a-contacter\/\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" title=\"\" alt=\"\" class=\"elementor-animation-float lazyload\" loading=\"lazy\" data-src=\"https:\/\/www.schaaf-gmbh.com\/wp-content\/uploads\/grundaufbau\/schaaf_ansprechpartner_mitarbeiter.jpg\">\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3fbeb8cc elementor-widget elementor-widget-heading\" data-id=\"3fbeb8cc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/www.schaaf-gmbh.com\/fr\/contacts\/apercu-les-personnes-a-contacter\/\">Personnes \u00e0 contacter<\/a><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-461bbe87 elementor-invisible\" data-id=\"461bbe87\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeIn&quot;}\">\r\n\t\t\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\r\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-48e68955 elementor-widget elementor-widget-image\" data-id=\"48e68955\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.schaaf-gmbh.com\/fr\/unternehmen\/\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" title=\"unternehmen_gebaeude\" alt=\"Schaaf Erkelenz Firmengeb\u00e4ude\" class=\"elementor-animation-float lazyload\" loading=\"lazy\" data-src=\"https:\/\/www.schaaf-gmbh.com\/wp-content\/uploads\/schaaf_deutschland_werk1.jpg\">\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cbcd266 elementor-widget elementor-widget-heading\" data-id=\"cbcd266\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/www.schaaf-gmbh.com\/fr\/unternehmen\/\">La soci\u00e9t\u00e9<\/a><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/section>\r\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/section>\r\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Ecrou hydraulique PG12 Tensionnement axial de boulons par un systeme hydraulique de haute pression R\u00e9duction des co\u00fbts &#8211; Puissant &#8211; R\u00e9utilisable Les \u00e9crous hydrauliques ne n\u00e9cessitent pas de projection de filetage comme les tendeurs de boulons, ce qui permet leur utilisation dans des constructions anciennes pour remplacer les connexions \u00e0 boulon serr\u00e9es avec cl\u00e9 dynamom\u00e9trique. [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":34867,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-34743","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.6 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Ecrou hydraulique HM PG12 - SCHAAF - Leading joining technology<\/title>\n<meta name=\"description\" content=\"Connexion de composants \u00e0 un \u00e9tage utilisant une pression hydraulique \u00e9lev\u00e9e pour g\u00e9n\u00e9rer des forces de d\u00e9placement axial avec des pistons \u00e9tag\u00e9s.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.schaaf-gmbh.com\/fr\/elements-dassemblage\/hydraulikmutter\/hm-pg12\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ecrou hydraulique HM PG12\" \/>\n<meta property=\"og:description\" content=\"Connexion de composants \u00e0 un \u00e9tage utilisant une pression hydraulique \u00e9lev\u00e9e pour g\u00e9n\u00e9rer des forces de d\u00e9placement axial avec des pistons \u00e9tag\u00e9s.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.schaaf-gmbh.com\/fr\/elements-dassemblage\/hydraulikmutter\/hm-pg12\/\" \/>\n<meta property=\"og:site_name\" content=\"SCHAAF - Leading joining technology\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Schaaf.gmbh.de\/\" \/>\n<meta property=\"article:modified_time\" content=\"2024-11-18T13:33:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.schaaf-gmbh.com\/wp-content\/uploads\/produkte\/piktogramme-pg\/pg12.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"22 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.schaaf-gmbh.com\\\/fr\\\/elements-dassemblage\\\/hydraulikmutter\\\/hm-pg12\\\/\",\"url\":\"https:\\\/\\\/www.schaaf-gmbh.com\\\/fr\\\/elements-dassemblage\\\/hydraulikmutter\\\/hm-pg12\\\/\",\"name\":\"Ecrou hydraulique HM PG12 - SCHAAF - Leading joining technology\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.schaaf-gmbh.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.schaaf-gmbh.com\\\/fr\\\/elements-dassemblage\\\/hydraulikmutter\\\/hm-pg12\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.schaaf-gmbh.com\\\/fr\\\/elements-dassemblage\\\/hydraulikmutter\\\/hm-pg12\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.schaaf-gmbh.com\\\/wp-content\\\/uploads\\\/produkte\\\/piktogramme-pg\\\/pg12.png\",\"datePublished\":\"2021-08-05T12:10:37+00:00\",\"dateModified\":\"2024-11-18T13:33:58+00:00\",\"description\":\"Connexion de composants \u00e0 un \u00e9tage utilisant une pression hydraulique \u00e9lev\u00e9e pour g\u00e9n\u00e9rer des forces de d\u00e9placement axial avec des pistons \u00e9tag\u00e9s.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.schaaf-gmbh.com\\\/fr\\\/elements-dassemblage\\\/hydraulikmutter\\\/hm-pg12\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.schaaf-gmbh.com\\\/fr\\\/elements-dassemblage\\\/hydraulikmutter\\\/hm-pg12\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.schaaf-gmbh.com\\\/fr\\\/elements-dassemblage\\\/hydraulikmutter\\\/hm-pg12\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.schaaf-gmbh.com\\\/wp-content\\\/uploads\\\/produkte\\\/piktogramme-pg\\\/pg12.png\",\"contentUrl\":\"https:\\\/\\\/www.schaaf-gmbh.com\\\/wp-content\\\/uploads\\\/produkte\\\/piktogramme-pg\\\/pg12.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.schaaf-gmbh.com\\\/fr\\\/elements-dassemblage\\\/hydraulikmutter\\\/hm-pg12\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.schaaf-gmbh.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00c9l\u00e9ments d&rsquo;assemblage\",\"item\":\"https:\\\/\\\/www.schaaf-gmbh.com\\\/fr\\\/elements-dassemblage\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"\u00c9crous hydrauliques\",\"item\":\"https:\\\/\\\/www.schaaf-gmbh.com\\\/fr\\\/elements-dassemblage\\\/hydraulikmutter\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"HM PG12\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.schaaf-gmbh.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.schaaf-gmbh.com\\\/fr\\\/\",\"name\":\"SCHAAF - Leading joining technology\",\"description\":\"Leading joining technology\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.schaaf-gmbh.com\\\/fr\\\/#organization\"},\"alternateName\":\"SCHAAF GmbH & Co. KG\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.schaaf-gmbh.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.schaaf-gmbh.com\\\/fr\\\/#organization\",\"name\":\"Schaaf GmbH & Co. KG\",\"alternateName\":\"SCHAAF GmbH & Co. KG\",\"url\":\"https:\\\/\\\/www.schaaf-gmbh.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.schaaf-gmbh.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.schaaf-gmbh.com\\\/wp-content\\\/uploads\\\/grundaufbau\\\/apple_176x176.png\",\"contentUrl\":\"https:\\\/\\\/www.schaaf-gmbh.com\\\/wp-content\\\/uploads\\\/grundaufbau\\\/apple_176x176.png\",\"width\":176,\"height\":176,\"caption\":\"Schaaf GmbH & Co. KG\"},\"image\":{\"@id\":\"https:\\\/\\\/www.schaaf-gmbh.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Schaaf.gmbh.de\\\/\",\"https:\\\/\\\/www.instagram.com\\\/schaaf.gmbh\\\/\",\"https:\\\/\\\/de.linkedin.com\\\/company\\\/schaaf-gmbh-com\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCJfkln8LVDeGgV-V8yzePBQ\"],\"slogan\":\"Leading joining technology\",\"address\":{\"@type\":\"PostalAddress\",\"streetAddress\":\"Br\u00fcsseler Allee 22\",\"postalCode\":\"41812\",\"addressLocality\":\"Erkelenz\",\"addressRegion\":\"Nordrhein-Westfalen\",\"addressCountry\":\"DE\"},\"areaServed\":{\"@type\":\"Place\",\"name\":\"Worldwide\"},\"contactPoint\":[{\"@type\":\"ContactPoint\",\"contactType\":\"general inquiries\",\"telephone\":\"+49-2431-97770-0\",\"email\":\"info@schaaf-gmbh.com\",\"areaServed\":\"Worldwide\",\"availableLanguage\":[{\"@type\":\"Language\",\"name\":\"Deutsch\",\"alternateName\":\"de\"},{\"@type\":\"Language\",\"name\":\"English\",\"alternateName\":\"en\"},{\"@type\":\"Language\",\"name\":\"Fran\u00e7ais\",\"alternateName\":\"fr\"},{\"@type\":\"Language\",\"name\":\"Espa\u00f1ol\",\"alternateName\":\"es\"},{\"@type\":\"Language\",\"name\":\"\u4e2d\u6587\",\"alternateName\":\"zh\"},{\"@type\":\"Language\",\"name\":\"\u0420\u0443\u0441\u0441\u043a\u0438\u0439\",\"alternateName\":\"ru\"}]}],\"knowsAbout\":[\"Verbindungstechnik\",\"Schraubenspannvorrichtungen\",\"Hydraulikmuttern\",\"Hydraulische Hochdruckwerkzeuge\",\"Bolt Tensioning\",\"Flanschverbindungen\",\"Industrielle Schraubverbindungen\",\"Verbindungsbolzen\",\"Wellen- und Achsverbindungen\",\"ExpaTen\",\"GripLoc\",\"GripCon\",\"TTG-Technologie\"],\"hasCredential\":[{\"@type\":\"EducationalOccupationalCredential\",\"credentialCategory\":\"Certification\",\"name\":\"DIN EN ISO 9001:2015\"}],\"description\":\"Die SCHAAF GmbH & Co. KG entwickelt und fertigt seit 1954 Verbindungstechnik sowie hydraulische Hochdruckwerkzeuge f\u00fcr industrielle Anwendungen weltweit. Zum Produktspektrum geh\u00f6ren Schraubenspannvorrichtungen, Hydraulikmuttern, ExpaTen, GripLoc, GripCon, Verbindungsbolzen und die patentierte TTG-Technologie. Die L\u00f6sungen kommen unter anderem im Maschinenbau, in der Windenergie, im Schiffbau sowie in der Energie- und Prozessindustrie zum Einsatz.\",\"email\":\"info@schaaf-gmbh.com\",\"telephone\":\"+49 \u2013 24 31 \u2013 9 77 70-0\",\"legalName\":\"Schaaf GmbH & Co. KG\",\"foundingDate\":\"1954-01-01\",\"vatID\":\"DE 814 64 67 52\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"201\",\"maxValue\":\"500\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Ecrou hydraulique HM PG12 - SCHAAF - Leading joining technology","description":"Connexion de composants \u00e0 un \u00e9tage utilisant une pression hydraulique \u00e9lev\u00e9e pour g\u00e9n\u00e9rer des forces de d\u00e9placement axial avec des pistons \u00e9tag\u00e9s.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.schaaf-gmbh.com\/fr\/elements-dassemblage\/hydraulikmutter\/hm-pg12\/","og_locale":"fr_FR","og_type":"article","og_title":"Ecrou hydraulique HM PG12","og_description":"Connexion de composants \u00e0 un \u00e9tage utilisant une pression hydraulique \u00e9lev\u00e9e pour g\u00e9n\u00e9rer des forces de d\u00e9placement axial avec des pistons \u00e9tag\u00e9s.","og_url":"https:\/\/www.schaaf-gmbh.com\/fr\/elements-dassemblage\/hydraulikmutter\/hm-pg12\/","og_site_name":"SCHAAF - Leading joining technology","article_publisher":"https:\/\/www.facebook.com\/Schaaf.gmbh.de\/","article_modified_time":"2024-11-18T13:33:58+00:00","og_image":[{"url":"https:\/\/www.schaaf-gmbh.com\/wp-content\/uploads\/produkte\/piktogramme-pg\/pg12.png","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"22 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.schaaf-gmbh.com\/fr\/elements-dassemblage\/hydraulikmutter\/hm-pg12\/","url":"https:\/\/www.schaaf-gmbh.com\/fr\/elements-dassemblage\/hydraulikmutter\/hm-pg12\/","name":"Ecrou hydraulique HM PG12 - SCHAAF - Leading joining technology","isPartOf":{"@id":"https:\/\/www.schaaf-gmbh.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.schaaf-gmbh.com\/fr\/elements-dassemblage\/hydraulikmutter\/hm-pg12\/#primaryimage"},"image":{"@id":"https:\/\/www.schaaf-gmbh.com\/fr\/elements-dassemblage\/hydraulikmutter\/hm-pg12\/#primaryimage"},"thumbnailUrl":"https:\/\/www.schaaf-gmbh.com\/wp-content\/uploads\/produkte\/piktogramme-pg\/pg12.png","datePublished":"2021-08-05T12:10:37+00:00","dateModified":"2024-11-18T13:33:58+00:00","description":"Connexion de composants \u00e0 un \u00e9tage utilisant une pression hydraulique \u00e9lev\u00e9e pour g\u00e9n\u00e9rer des forces de d\u00e9placement axial avec des pistons \u00e9tag\u00e9s.","breadcrumb":{"@id":"https:\/\/www.schaaf-gmbh.com\/fr\/elements-dassemblage\/hydraulikmutter\/hm-pg12\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.schaaf-gmbh.com\/fr\/elements-dassemblage\/hydraulikmutter\/hm-pg12\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.schaaf-gmbh.com\/fr\/elements-dassemblage\/hydraulikmutter\/hm-pg12\/#primaryimage","url":"https:\/\/www.schaaf-gmbh.com\/wp-content\/uploads\/produkte\/piktogramme-pg\/pg12.png","contentUrl":"https:\/\/www.schaaf-gmbh.com\/wp-content\/uploads\/produkte\/piktogramme-pg\/pg12.png"},{"@type":"BreadcrumbList","@id":"https:\/\/www.schaaf-gmbh.com\/fr\/elements-dassemblage\/hydraulikmutter\/hm-pg12\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.schaaf-gmbh.com\/fr\/"},{"@type":"ListItem","position":2,"name":"\u00c9l\u00e9ments d&rsquo;assemblage","item":"https:\/\/www.schaaf-gmbh.com\/fr\/elements-dassemblage\/"},{"@type":"ListItem","position":3,"name":"\u00c9crous hydrauliques","item":"https:\/\/www.schaaf-gmbh.com\/fr\/elements-dassemblage\/hydraulikmutter\/"},{"@type":"ListItem","position":4,"name":"HM PG12"}]},{"@type":"WebSite","@id":"https:\/\/www.schaaf-gmbh.com\/fr\/#website","url":"https:\/\/www.schaaf-gmbh.com\/fr\/","name":"SCHAAF - Leading joining technology","description":"Leading joining technology","publisher":{"@id":"https:\/\/www.schaaf-gmbh.com\/fr\/#organization"},"alternateName":"SCHAAF GmbH & Co. KG","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.schaaf-gmbh.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.schaaf-gmbh.com\/fr\/#organization","name":"Schaaf GmbH & Co. KG","alternateName":"SCHAAF GmbH & Co. KG","url":"https:\/\/www.schaaf-gmbh.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.schaaf-gmbh.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.schaaf-gmbh.com\/wp-content\/uploads\/grundaufbau\/apple_176x176.png","contentUrl":"https:\/\/www.schaaf-gmbh.com\/wp-content\/uploads\/grundaufbau\/apple_176x176.png","width":176,"height":176,"caption":"Schaaf GmbH & Co. KG"},"image":{"@id":"https:\/\/www.schaaf-gmbh.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Schaaf.gmbh.de\/","https:\/\/www.instagram.com\/schaaf.gmbh\/","https:\/\/de.linkedin.com\/company\/schaaf-gmbh-com","https:\/\/www.youtube.com\/channel\/UCJfkln8LVDeGgV-V8yzePBQ"],"slogan":"Leading joining technology","address":{"@type":"PostalAddress","streetAddress":"Br\u00fcsseler Allee 22","postalCode":"41812","addressLocality":"Erkelenz","addressRegion":"Nordrhein-Westfalen","addressCountry":"DE"},"areaServed":{"@type":"Place","name":"Worldwide"},"contactPoint":[{"@type":"ContactPoint","contactType":"general inquiries","telephone":"+49-2431-97770-0","email":"info@schaaf-gmbh.com","areaServed":"Worldwide","availableLanguage":[{"@type":"Language","name":"Deutsch","alternateName":"de"},{"@type":"Language","name":"English","alternateName":"en"},{"@type":"Language","name":"Fran\u00e7ais","alternateName":"fr"},{"@type":"Language","name":"Espa\u00f1ol","alternateName":"es"},{"@type":"Language","name":"\u4e2d\u6587","alternateName":"zh"},{"@type":"Language","name":"\u0420\u0443\u0441\u0441\u043a\u0438\u0439","alternateName":"ru"}]}],"knowsAbout":["Verbindungstechnik","Schraubenspannvorrichtungen","Hydraulikmuttern","Hydraulische Hochdruckwerkzeuge","Bolt Tensioning","Flanschverbindungen","Industrielle Schraubverbindungen","Verbindungsbolzen","Wellen- und Achsverbindungen","ExpaTen","GripLoc","GripCon","TTG-Technologie"],"hasCredential":[{"@type":"EducationalOccupationalCredential","credentialCategory":"Certification","name":"DIN EN ISO 9001:2015"}],"description":"Die SCHAAF GmbH & Co. KG entwickelt und fertigt seit 1954 Verbindungstechnik sowie hydraulische Hochdruckwerkzeuge f\u00fcr industrielle Anwendungen weltweit. Zum Produktspektrum geh\u00f6ren Schraubenspannvorrichtungen, Hydraulikmuttern, ExpaTen, GripLoc, GripCon, Verbindungsbolzen und die patentierte TTG-Technologie. Die L\u00f6sungen kommen unter anderem im Maschinenbau, in der Windenergie, im Schiffbau sowie in der Energie- und Prozessindustrie zum Einsatz.","email":"info@schaaf-gmbh.com","telephone":"+49 \u2013 24 31 \u2013 9 77 70-0","legalName":"Schaaf GmbH & Co. KG","foundingDate":"1954-01-01","vatID":"DE 814 64 67 52","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"201","maxValue":"500"}}]}},"_links":{"self":[{"href":"https:\/\/www.schaaf-gmbh.com\/fr\/wp-json\/wp\/v2\/pages\/34743","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.schaaf-gmbh.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.schaaf-gmbh.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.schaaf-gmbh.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.schaaf-gmbh.com\/fr\/wp-json\/wp\/v2\/comments?post=34743"}],"version-history":[{"count":2,"href":"https:\/\/www.schaaf-gmbh.com\/fr\/wp-json\/wp\/v2\/pages\/34743\/revisions"}],"predecessor-version":[{"id":61117,"href":"https:\/\/www.schaaf-gmbh.com\/fr\/wp-json\/wp\/v2\/pages\/34743\/revisions\/61117"}],"up":[{"embeddable":true,"href":"https:\/\/www.schaaf-gmbh.com\/fr\/wp-json\/wp\/v2\/pages\/34867"}],"wp:attachment":[{"href":"https:\/\/www.schaaf-gmbh.com\/fr\/wp-json\/wp\/v2\/media?parent=34743"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}